{"id":2621,"date":"2024-09-12T18:19:27","date_gmt":"2024-09-12T16:19:27","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2621"},"modified":"2024-09-12T18:19:29","modified_gmt":"2024-09-12T16:19:29","slug":"tony-ferguson-su-historia-altura-peso-edad-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/","title":{"rendered":"Tony Ferguson: historia, altura, peso, edad, patrimonio"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Breve resumen del art\u00edculo<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Dato<\/strong><\/th><th><strong>Detalle<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Nombre y apellidos<\/strong><\/td><td>Tony Ferguson<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-taille\/\">Talla<\/a><\/strong><\/td><td>1m83<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong><\/td><td>77 kg<\/td><\/tr><tr><td><strong>Edad<\/strong><\/td><td>40 a\u00f1os (nacido el 12 de febrero de 1984)<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-fortune\/\">Fortuna<\/a> estimado<\/strong><\/td><td>Alrededor de 4 millones de d\u00f3lares<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h3 class=\"wp-block-heading\">Introducci\u00f3n<\/h3>\n\n\n\n<p> Cuando uno piensa en Tony Ferguson, inmediatamente piensa en peleas \u00e9picas, un estilo extraordinario y una capacidad para sorprender incluso a los luchadores m\u00e1s experimentados. Pero, \u00bfqui\u00e9n es realmente el hombre que se esconde tras el apodo de \"El Cucuy\"? Para entender a Tony Ferguson, tenemos que remontarnos a sus inicios, explorar su carrera y analizar el impacto que ha tenido en el mundo de las artes marciales mixtas (MMA). Porque Tony no es s\u00f3lo victorias y golpes bien dados, sino tambi\u00e9n un esp\u00edritu de lucha y una historia \u00fanica. Tony Ferguson es un luchador que se niega a quedarse en el molde. En un mundo en el que la t\u00e9cnica es crucial, \u00e9l a\u00f1ade una dimensi\u00f3n impredecible a su estilo, lo que le convierte en un rival temido. Es el tipo de boxeador al que nunca se le puede coger el truco, y eso hace que sea a\u00fan m\u00e1s fascinante de seguir, tanto para los aficionados como para los adversarios. En este art\u00edculo voy a hablarle de su pasado, de su f\u00edsico curtido en mil batallas, de su mentalidad inquebrantable y de c\u00f3mo ha construido una aut\u00e9ntica fortuna.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tony Ferguson: Historia, altura, peso, edad, patrimonio <\/h2>\n\n\n\n<p>Cuando te interesas por Tony Ferguson, lo primero que te llama la atenci\u00f3n es que es un gran hombre. <a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/meilleur-sac-de-frappe-boxe\/\">hit<\/a>es su apodo: \"El Cucuy\", el hombre del saco en espa\u00f1ol. Y francamente, no es casualidad. Tony Ferguson tiene ese aura de peligro constante, alguien que parece aparecer de la nada, que no sigue ninguna regla preestablecida. Nacido en Oxnard, California, el 12 de febrero de 1984, Ferguson creci\u00f3 en una familia con ra\u00edces mexicanas, una herencia que lleva con orgullo. No es s\u00f3lo un luchador, es un aut\u00e9ntico t\u00e9cnico, con una s\u00f3lida formaci\u00f3n en lucha libre, que perfeccion\u00f3 en la escuela secundaria. No tom\u00f3 el camino f\u00e1cil; es un tipo que trabaj\u00f3 duro para llegar donde est\u00e1, acumulando experiencia en varias disciplinas antes de dedicarse a las MMA. Y el resultado est\u00e1 ah\u00ed. Tanto si eres fan del jiu-jitsu brasile\u00f1o como del striking, hay algo para todo el mundo viendo pelear a Tony. Lo que hace tan especial a Ferguson es su capacidad para mezclar estas t\u00e9cnicas con una fluidez desconcertante. Pasa de un agarre en el suelo a un codazo volador como si fuera una mera formalidad. Ha desarrollado esta versatilidad buscando mejorar constantemente, neg\u00e1ndose a dormirse en los laureles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un f\u00edsico construido para el combate <\/h3>\n\n\n\n<p>A primera vista, puede que Tony Ferguson no tenga la imponente estatura de algunos pesos pesados, pero ese es precisamente su punto fuerte. Con su <strong>1m83<\/strong> para <strong>77 kg<\/strong>Es la encarnaci\u00f3n perfecta de la categor\u00eda de peso ligero. Lo que le hace tan impresionante no es s\u00f3lo su tama\u00f1o, sino la forma en que utiliza cada cent\u00edmetro y cada kilo para desequilibrar a sus oponentes. La divisi\u00f3n de los pesos ligeros es famosa por su velocidad e intensidad, pero Tony a\u00f1ade un toque de brutalidad y resistencia que a menudo marca la diferencia. Lo que le distingue es su capacidad de aguante. Hay luchadores que se derrumban tras unos cuantos golpes bien asestados. Tony no. \u00c9l est\u00e1 ah\u00ed los cinco asaltos, listo para recibir tanto como da. Y si alguna vez has asistido a uno de sus combates, sabr\u00e1s que nunca se echa atr\u00e1s. Su f\u00edsico es sin duda una ventaja, pero es su mente de acero la que le permite ir m\u00e1s all\u00e1 de sus l\u00edmites. Su cuerpo es como una m\u00e1quina bien engrasada, capaz de soportar una enorme presi\u00f3n y seguir avanzando. Es flexible, explosivo y, sobre todo, sabe perfectamente cu\u00e1ndo y c\u00f3mo utilizar cada m\u00fasculo y cada movimiento para derribar a su adversario. Es este dominio de su f\u00edsico lo que le ha permitido sobrevivir y brillar en una divisi\u00f3n tan competitiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Fuerza mental: Tony Ferguson, el esp\u00edritu indomable <\/h3>\n\n\n\n<p>Cuando ves pelear a Tony Ferguson, no s\u00f3lo impresiona su t\u00e9cnica. Es tambi\u00e9n su mentalidad. Hay algo inquebrantable en \u00e9l. Tienes la impresi\u00f3n de que nada puede pararle. Y eso es raro. Muy raro. Es como si cada golpe que recibe le hiciera m\u00e1s fuerte, m\u00e1s decidido. Su apodo \"El Cucuy\" refleja perfectamente el aura casi sobrenatural que desprende cuando est\u00e1 en la jaula. En los deportes de combate, la fuerza mental es a menudo lo que marca la diferencia entre la victoria y la derrota. Tony lo comprendi\u00f3 muy pronto. Tiene una capacidad incre\u00edble para mantener la calma, incluso bajo presi\u00f3n. En 2017, cuando gan\u00f3 el t\u00edtulo interino de peso ligero de la UFC, lo hizo con una confianza inquebrantable, aun sabiendo que el camino por delante estar\u00eda lleno de escollos. Es una mentalidad que ha forjado a lo largo de los a\u00f1os, a trav\u00e9s de intensos entrenamientos, victorias sorprendentes y derrotas desgarradoras. Donde muchos se habr\u00edan derrumbado tras duras derrotas, Tony Ferguson ha vuelto m\u00e1s fuerte. Es un modelo de resistencia para los j\u00f3venes deportistas. Incluso cuando est\u00e1 en su momento m\u00e1s bajo, mantiene la cabeza alta. <a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/meilleur-casque-de-boxe\/\">cabeza<\/a> listo para volver a luchar. Es esta capacidad de levantarse de nuevo lo que le convierte en un luchador \u00fanico, un verdadero guerrero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Los altibajos de una carrera legendaria <\/h3>\n\n\n\n<p>La carrera de Tony Ferguson no se compone simplemente de victorias deslumbrantes. Como todos los grandes campeones, tambi\u00e9n sufri\u00f3 derrotas. Pero mientras muchos se contentan con hablar de sus victorias, es importante recordar que fueron sus momentos dif\u00edciles los que le forjaron. Despu\u00e9s de acumular 12 victorias consecutivas, una impresionante racha que le impuls\u00f3 a la cima de la UFC, Ferguson sufri\u00f3 un inesperado rev\u00e9s contra Justin Gaethje en 2020. Fue una derrota dolorosa que podr\u00eda haber marcado el final para muchos luchadores. Pero Tony no ve las derrotas como fracasos. Las ve como oportunidades para aprender. Cada pelea, ganada o perdida, es una lecci\u00f3n. Es esta filosof\u00eda la que le hace seguir adelante, incluso cuando las cosas parecen ir mal. Sabe que el camino hacia la gloria nunca es lineal, y es esta perseverancia lo que le hace tan especial. Lo fascinante de Tony es que siempre ha sabido reinventarse. Tanto en su estilo de lucha como en su preparaci\u00f3n f\u00edsica y mental, evoluciona constantemente. Se niega a quedarse estancado. Por eso, incluso despu\u00e9s de las derrotas, los aficionados siguen creyendo en \u00e9l. Porque saben que es capaz de cambiar las cosas en cualquier momento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La fortuna de Tony Ferguson: un luchador que sac\u00f3 provecho <\/h2>\n\n\n\n<p>Tony Ferguson no es s\u00f3lo un boxeador, sino tambi\u00e9n un astuto hombre de negocios. Su fortuna, estimada en unos <strong>4 millones<\/strong>El \u00e9xito de Tony es el resultado no s\u00f3lo de a\u00f1os de duro trabajo, sino tambi\u00e9n de una inteligente gesti\u00f3n de su carrera. A diferencia de algunos luchadores que gastan su dinero tan r\u00e1pido como lo ganan, Tony ha conseguido diversificar sus ingresos. Por supuesto, las ganancias de sus combates constituyen una gran parte de su fortuna, pero tambi\u00e9n ha conseguido monetizar su imagen a trav\u00e9s de contratos publicitarios y apariciones en los medios de comunicaci\u00f3n. Lo extraordinario de Tony es que no es s\u00f3lo un luchador. Tambi\u00e9n es un hombre de negocios. Es consciente de la importancia de forjarse una imagen fuera del oct\u00e1gono. Esto le ha permitido seguir siendo relevante, incluso cuando no luchaba activamente. Ya sea a trav\u00e9s de asociaciones con marcas o de colaboraciones con otros deportistas, Tony ha sabido maximizar sus ingresos sin dejar de ser fiel a s\u00ed mismo. Es un modelo a seguir para los j\u00f3venes luchadores que quieren triunfar no s\u00f3lo en el ring, sino tambi\u00e9n fuera de \u00e9l. Su carrera nos demuestra que la disciplina y la inteligencia financiera son tan importantes como la fuerza y la t\u00e9cnica en los deportes de combate.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una carrera en movimiento <\/h3>\n\n\n\n<p>Incluso despu\u00e9s de llegar a la cima, Tony Ferguson nunca dej\u00f3 de buscar mejorar. Podr\u00eda haberse dormido en los laureles tras ganar el t\u00edtulo interino del peso ligero, pero ese no es su estilo. Para \u00e9l, cada combate es una nueva oportunidad de demostrar que sigue siendo uno de los mejores. Esta b\u00fasqueda constante de la perfecci\u00f3n es una cualidad que pocos luchadores poseen a este nivel. Sigue entren\u00e1ndose intensamente, buscando siempre perfeccionar su arte. Para Tony, el aprendizaje nunca tiene fin. Eso es parte de lo que le hace tan inspirador. Incluso a los 40, sigue d\u00e1ndolo todo en cada combate, neg\u00e1ndose a que su edad le defina. Su historia est\u00e1 lejos de terminar, y es seguro que Tony Ferguson tiene reservadas algunas sorpresas m\u00e1s para sus fans.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conclusi\u00f3n <\/h4>\n\n\n\n<p>Tony Ferguson es mucho m\u00e1s que un luchador: es una leyenda viva de las artes marciales mixtas. A sus 40 a\u00f1os, puede parecer que su carrera est\u00e1 llegando a su fin, pero si algo nos ha ense\u00f1ado la historia es que nunca hay que subestimar a \"El Cucuy\". Desde sus humildes comienzos hasta su impresionante fortuna, Tony ha demostrado que tiene lo que hace falta para triunfar, tanto dentro como fuera de la jaula. Su mentalidad de acero, su capacidad para aguantar los golpes y levantarse despu\u00e9s de cada ca\u00edda lo convierten en una verdadera inspiraci\u00f3n. As\u00ed que, si buscas un modelo a seguir, ya sea en el deporte o en la vida, Tony Ferguson es sin duda un hombre al que estudiar de cerca.<\/p>\n\n\n\n<p>Fuentes : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4927\">Boxeo Wiki <\/a><\/strong><\/p>\n\n\n\n<p>V\u00e9ase tambi\u00e9n :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4928\"> Sitio web oficial de los veteranos<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Resumen r\u00e1pido del art\u00edculo en pocas palabras Dato Detalle Nombre completo Tony Ferguson Altura 1m83 Peso 77 kg Edad 40 (nacido el 12 de febrero de 1984) Fortuna estimada Alrededor de 4 millones de d\u00f3lares Introducci\u00f3n Cuando se piensa en Tony Ferguson, inmediatamente se piensa en peleas \u00e9picas, un estilo extraordinario ... <a title=\"Tony Ferguson: historia, altura, peso, edad, patrimonio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/\" aria-label=\"Leer m\u00e1s sobre Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":2,"featured_media":2626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Tony Ferguson est bien plus qu&#039;un simple combattant, il est une l\u00e9gende vivante des arts martiaux mixtes. Avec ses 40 ans\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Tony Ferguson est bien plus qu&#039;un simple combattant, il est une l\u00e9gende vivante des arts martiaux mixtes. Avec ses 40 ans\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T16:19:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T16:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/images__12_-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-09-12T16:19:27+00:00\",\"dateModified\":\"2024-09-12T16:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/\"},\"wordCount\":1821,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/images__12_-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/\",\"name\":\"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/images__12_-removebg-preview.png\",\"datePublished\":\"2024-09-12T16:19:27+00:00\",\"dateModified\":\"2024-09-12T16:19:29+00:00\",\"description\":\"Tony Ferguson est bien plus qu'un simple combattant, il est une l\u00e9gende vivante des arts martiaux mixtes. Avec ses 40 ans\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/images__12_-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/images__12_-removebg-preview.png\",\"width\":275,\"height\":183,\"caption\":\"Tony Ferguson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/tony-ferguson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tony Ferguson: historia, altura, peso, edad, patrimonio","description":"Tony Ferguson es mucho m\u00e1s que un luchador: es una leyenda viva de las artes marciales mixtas. A sus 40 a\u00f1os","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/","og_locale":"es_ES","og_type":"article","og_title":"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Tony Ferguson est bien plus qu'un simple combattant, il est une l\u00e9gende vivante des arts martiaux mixtes. Avec ses 40 ans","og_url":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/","og_site_name":"Boxeur PRO","article_published_time":"2024-09-12T16:19:27+00:00","article_modified_time":"2024-09-12T16:19:29+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/images__12_-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maxime","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-09-12T16:19:27+00:00","dateModified":"2024-09-12T16:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/"},"wordCount":1821,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/es\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/images__12_-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/","url":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/","name":"Tony Ferguson: historia, altura, peso, edad, patrimonio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/images__12_-removebg-preview.png","datePublished":"2024-09-12T16:19:27+00:00","dateModified":"2024-09-12T16:19:29+00:00","description":"Tony Ferguson es mucho m\u00e1s que un luchador: es una leyenda viva de las artes marciales mixtas. A sus 40 a\u00f1os","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/images__12_-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/images__12_-removebg-preview.png","width":275,"height":183,"caption":"Tony Ferguson"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/es\/tony-ferguson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Tony Ferguson : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/es\/#website","url":"https:\/\/boxeur-pro.fr\/es\/","name":"Boxeador PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/es\/#organization","name":"Boxeador PRO","url":"https:\/\/boxeur-pro.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/es\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts\/2621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/comments?post=2621"}],"version-history":[{"count":2,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts\/2621\/revisions"}],"predecessor-version":[{"id":2633,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts\/2621\/revisions\/2633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/media\/2626"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/media?parent=2621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/categories?post=2621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/tags?post=2621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}