{"id":2666,"date":"2024-09-25T16:28:14","date_gmt":"2024-09-25T14:28:14","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2666"},"modified":"2024-09-25T16:28:15","modified_gmt":"2024-09-25T14:28:15","slug":"jason-jackson-su-historia-altura-peso-edad-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/","title":{"rendered":"Jason Jackson: historia, altura, peso, edad, patrimonio"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>Breve resumen del art\u00edculo<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Aspecto<\/strong><\/th><th><strong>Detalle<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Nombre y apellidos<\/strong><\/td><td>Jason Marlon Jackson<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-taille\/\">Talla<\/a><\/strong><\/td><td><strong>6'1\u2033 (1,85 m)<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong><\/td><td><strong>170-177 lbs (77-80 kg)<\/strong><\/td><\/tr><tr><td><strong>Edad<\/strong><\/td><td><strong>33 a\u00f1os (nacido en 1990)<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-fortune\/\">Fortuna<\/a><\/strong><\/td><td><strong>2 millones<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Introducci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Cuando se trata de Jason Jackson, es dif\u00edcil no sentirse impresionado por su carrera. Originario de Kingston (Jamaica), se ha hecho un nombre en el mundo de las MMA gracias a su estilo agresivo y a su inquebrantable determinaci\u00f3n. No es casualidad que le apoden \"La m\u00e1quina de patear culos\": cada combate es una demostraci\u00f3n de potencia, t\u00e9cnica e inteligencia. En este art\u00edculo, voy a sumergirle en el mundo de este atleta, explorando su historia, sus \u00e9xitos, sus retos y, por supuesto, sus impresionantes estad\u00edsticas. Pero no se trata s\u00f3lo de los n\u00fameros, porque detr\u00e1s de cada victoria hay una historia, un viaje \u00fanico que ha hecho de Jason Jackson uno de los mejores luchadores de su generaci\u00f3n.<\/p>\n\n\n\n<p>La historia de Jackson es una historia de resistencia. A lo largo de los altibajos de su carrera, nunca se ha rendido. Desde sus primeros d\u00edas en competiciones locales hasta convertirse en campe\u00f3n del peso welter en Bellator, siempre ha demostrado una voluntad de ganar que pocos pueden igualar. Te mostrar\u00e9 por qu\u00e9 este hombre se ha convertido en una leyenda y por qu\u00e9 a\u00fan tiene mucho que ofrecer al mundo de las MMA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Jason Jackson: un luchador con una carrera extraordinaria<\/h2>\n\n\n\n<p>La carrera de Jason Jackson ha sido un marat\u00f3n. Nacido en Kingston, se traslad\u00f3 r\u00e1pidamente a Estados Unidos para perseguir sus sue\u00f1os. Al principio no fue f\u00e1cil, ya que tuvo que hacer malabarismos con varios trabajos espor\u00e1dicos para financiar su entrenamiento. Pero lo que diferencia a Jason del resto es su inquebrantable voluntad. \u00c0 <strong>6'1\u2033 (1,85 m)<\/strong>De complexi\u00f3n atl\u00e9tica y una flexibilidad poco com\u00fan para su tama\u00f1o, ha utilizado su f\u00edsico en beneficio propio desde el principio de su carrera.<\/p>\n\n\n\n<p>Visite <strong>2012<\/strong>debut\u00f3 profesionalmente contra futuros grandes de la UFC como <strong>Colby Covington<\/strong>. Este dif\u00edcil comienzo s\u00f3lo sirvi\u00f3 para aumentar su motivaci\u00f3n. Sus primeras victorias le pusieron r\u00e1pidamente en el punto de mira. Pero eso no es todo: Jason es un luchador polivalente. Tanto de pie como en el suelo, sabe adaptarse a sus adversarios. Esta capacidad para evolucionar constantemente y sorprender es lo que le ha llevado a ganar t\u00edtulos en organizaciones tan prestigiosas como <strong>Titan FC<\/strong> y <strong>Bellator MMA<\/strong>.<\/p>\n\n\n\n<p>Pero el \u00e9xito nunca es lineal. Tambi\u00e9n ha pasado por momentos dif\u00edciles, como lesiones que le han mantenido alejado de los ruedos. Sin embargo, cada obst\u00e1culo ha sido para \u00e9l una oportunidad de volver m\u00e1s fuerte. En 2023, gan\u00f3 el campeonato del peso welter en <strong>Bellator<\/strong>Su perseverancia es una lecci\u00f3n para todos los que siguen el deporte. Su perseverancia es una lecci\u00f3n para todos los que siguen el deporte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sus mayores \u00e9xitos en la MMA<\/h3>\n\n\n\n<p>Las cifras hablan por s\u00ed solas cuando se trata de la carrera de Jason Jackson. Con un r\u00e9cord de <strong>18 victorias y s\u00f3lo 5 derrotas<\/strong>de los cuales <strong>6 por KO<\/strong>Demostr\u00f3 que no estaba all\u00ed s\u00f3lo por diversi\u00f3n. Sin embargo, las estad\u00edsticas no lo dicen todo. Lo que hace especial a Jason es su enfoque met\u00f3dico de la lucha. En su lucha contra <strong>Paul Daley<\/strong>Por ejemplo, fue capaz de utilizar su t\u00e9cnica para dominar a un luchador que era famoso por su potente <a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/meilleur-sac-de-frappe-boxe\/\">hit<\/a>. Este combate, ganado por decisi\u00f3n un\u00e1nime, marc\u00f3 un punto de inflexi\u00f3n en su carrera.<\/p>\n\n\n\n<p>Jason tambi\u00e9n es famoso por su capacidad para prepararse mentalmente para cada desaf\u00edo. Antes de cada combate, estudia meticulosamente a sus oponentes, detecta sus puntos d\u00e9biles y los explota en la jaula. Esta capacidad de pensar como un estratega sin dejar de ser un guerrero le ha permitido llegar a lo m\u00e1s alto. Su <strong>9 victorias por decisi\u00f3n<\/strong> demuestran que tambi\u00e9n sabe manejar la presi\u00f3n a lo largo del tiempo, un elemento clave en las batallas de alto nivel.<\/p>\n\n\n\n<p>La lucha contra <strong>Douglas Lima<\/strong>uno de los momentos culminantes de su carrera, demostr\u00f3 la versatilidad de Jason. Enfrentado a un oponente formidable, mantuvo la calma y la concentraci\u00f3n, utilizando sus habilidades de lucha para imponerse.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">El hombre detr\u00e1s del luchador<\/h3>\n\n\n\n<p>Jason Jackson es algo m\u00e1s que un feroz luchador. Tras el apodo de \"La m\u00e1quina de patear culos\" se esconde un hombre humilde, profundamente apegado a sus ra\u00edces jamaicanas y a su familia. Casado con Yaniuska, Jason es un amoroso padre de familia, con dos hijos propios. <a href=\"https:\/\/boxeur-pro.fr\/es\/boxe\/mike-tyson-enfants\/\">ni\u00f1os<\/a> y dos de un matrimonio anterior. Este equilibrio entre su vida personal y profesional es sin duda una de las razones de su \u00e9xito duradero en un deporte tan exigente.<\/p>\n\n\n\n<p>Su traslado a Estados Unidos marc\u00f3 no s\u00f3lo el inicio de su carrera profesional, sino tambi\u00e9n una nueva vida para \u00e9l y su familia. Instalado en <strong>Miami<\/strong>Se entrena con algunos de los mejores luchadores del mundo, sin dejar de ser fiel a su identidad jamaicana. Cada vez que sube a la jaula, lleva consigo la herencia de su tierra natal.<\/p>\n\n\n\n<p>Fuera de la competici\u00f3n, Jason tambi\u00e9n se dedica a la tutor\u00eda. Se toma su tiempo para ayudar a los j\u00f3venes talentos a desarrollarse, compartiendo su experiencia y sus consejos. Es un hombre que entiende que la clave del \u00e9xito no est\u00e1 s\u00f3lo en el rendimiento f\u00edsico, sino tambi\u00e9n en la actitud y la mentalidad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una fortuna bien merecida: 2 millones de d\u00f3lares<\/h2>\n\n\n\n<p>Con una carrera tan rica, no es de extra\u00f1ar que Jason Jackson haya amasado una respetable fortuna. Estimada en <strong>2 millones<\/strong>Esta suma representa no s\u00f3lo sus victorias en los combates, sino tambi\u00e9n colaboraciones y oportunidades en los medios de comunicaci\u00f3n. Aunque no siempre se dan a conocer sus ganancias exactas, est\u00e1 claro que Jason ha aprovechado sus victorias para construir una s\u00f3lida fortuna.<\/p>\n\n\n\n<p>A diferencia de otros atletas que gastan sus ganancias r\u00e1pidamente, Jason es conocido por ser met\u00f3dico en la gesti\u00f3n de sus finanzas. Ha invertido en propiedades inmobiliarias y planea desarrollar negocios despu\u00e9s de su carrera en la MMA. No se trata s\u00f3lo de ganar dinero, sino tambi\u00e9n de asegurar su futuro y el de su familia.<\/p>\n\n\n\n<p>Lo que distingue a Jason es su humilde enfoque de la riqueza. A diferencia de algunos luchadores a los que les gusta alardear de su riqueza, Jackson prefiere la discreci\u00f3n. Para \u00e9l, lo m\u00e1s importante es garantizar la estabilidad a largo plazo de sus seres queridos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Sus \u00faltimas batallas y proyectos futuros<\/h3>\n\n\n\n<p>Los \u00faltimos combates de Jason Jackson han estado marcados por altibajos. En <strong>2024<\/strong>perdi\u00f3 su t\u00edtulo de peso welter ante <strong>Ramazan Kuramagomedov<\/strong> en una batalla \u00e9pica. Pero lejos de rendirse, Jackson ve esta derrota como una oportunidad para volver m\u00e1s fuerte. De hecho, ese es uno de sus puntos fuertes: nunca ve la derrota como un fracaso, sino como una lecci\u00f3n que aprender para futuras batallas.<\/p>\n\n\n\n<p>Con la UFC en el punto de mira, Jason no ha ocultado su ambici\u00f3n de unirse a la \u00e9lite mundial de las MMA. Para muchos expertos, posee todas las cualidades necesarias para brillar en esta organizaci\u00f3n. Su estilo, que combina potencia y estrategia, podr\u00eda permitirle imponerse a los mejores luchadores del mundo. \u00bfY qui\u00e9n sabe? Quiz\u00e1 dentro de unos a\u00f1os, Jason Jackson sea aclamado como uno de los m\u00e1s grandes de la historia de las MMA.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conclusi\u00f3n<\/strong><\/h3>\n\n\n\n<p>En conclusi\u00f3n, Jason Jackson es mucho m\u00e1s que un luchador. Es un hombre con una historia inspiradora, un atleta de innegable talento y un modelo de perseverancia. Su carrera es un ejemplo para todos aquellos que buscan sobresalir en su campo, ya sea en el deporte o en cualquier otro \u00e1mbito. \u00c0 <strong>33 a\u00f1os<\/strong>Con un palmar\u00e9s impresionante y una fortuna bien merecida, a\u00fan tiene mucho que ofrecer. Y aunque sus \u00faltimos combates han demostrado que a\u00fan tiene algunos retos por delante, est\u00e1 claro que Jason Jackson no ha dicho su \u00faltima palabra.<\/p>\n\n\n\n<p>Fuentes : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4983\">Boxeo Wiki <\/a><\/strong><\/p>\n\n\n\n<p>V\u00e9ase tambi\u00e9n :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4984\"> Sitio web oficial de los veteranos<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Resumen r\u00e1pido del art\u00edculo en breve Aspecto Detalle Nombre completo Jason Marlon Jackson Altura 1,85 m (6'1\u2033) Peso 77-80 kg (170-177 lbs) Edad 33 a\u00f1os (nacido en 1990) Fortuna 2 millones de d\u00f3lares Introducci\u00f3n Cuando se trata de Jason Jackson, es dif\u00edcil no ... <a title=\"Jason Jackson: historia, altura, peso, edad, patrimonio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/\" aria-label=\"Leer m\u00e1s sobre Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":2,"featured_media":2671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Pour conclure, Jason Jackson est bien plus qu&#039;un simple combattant. C&#039;est un homme avec une histoire inspirante, un athl\u00e8te\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Pour conclure, Jason Jackson est bien plus qu&#039;un simple combattant. C&#039;est un homme avec une histoire inspirante, un athl\u00e8te\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T14:28:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T14:28:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-09-25T14:28:14+00:00\",\"dateModified\":\"2024-09-25T14:28:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/\"},\"wordCount\":1467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/\",\"name\":\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"datePublished\":\"2024-09-25T14:28:14+00:00\",\"dateModified\":\"2024-09-25T14:28:15+00:00\",\"description\":\"Pour conclure, Jason Jackson est bien plus qu'un simple combattant. C'est un homme avec une histoire inspirante, un athl\u00e8te\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"width\":586,\"height\":426,\"caption\":\"Jason Jackson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/jason-jackson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/es\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jason Jackson: historia, altura, peso, edad, patrimonio","description":"En conclusi\u00f3n, Jason Jackson es mucho m\u00e1s que un luchador. Es un hombre con una historia inspiradora, un atleta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/","og_locale":"es_ES","og_type":"article","og_title":"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Pour conclure, Jason Jackson est bien plus qu'un simple combattant. C'est un homme avec une histoire inspirante, un athl\u00e8te","og_url":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/","og_site_name":"Boxeur PRO","article_published_time":"2024-09-25T14:28:14+00:00","article_modified_time":"2024-09-25T14:28:15+00:00","og_image":[{"width":586,"height":426,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maxime","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-09-25T14:28:14+00:00","dateModified":"2024-09-25T14:28:15+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/"},"wordCount":1467,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/es\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/","url":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/","name":"Jason Jackson: historia, altura, peso, edad, patrimonio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","datePublished":"2024-09-25T14:28:14+00:00","dateModified":"2024-09-25T14:28:15+00:00","description":"En conclusi\u00f3n, Jason Jackson es mucho m\u00e1s que un luchador. Es un hombre con una historia inspiradora, un atleta","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/es\/jason-jackson\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","width":586,"height":426,"caption":"Jason Jackson"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/es\/jason-jackson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/es\/#website","url":"https:\/\/boxeur-pro.fr\/es\/","name":"Boxeador PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/es\/#organization","name":"Boxeador PRO","url":"https:\/\/boxeur-pro.fr\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/es\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/es\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts\/2666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/comments?post=2666"}],"version-history":[{"count":3,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts\/2666\/revisions"}],"predecessor-version":[{"id":2678,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/posts\/2666\/revisions\/2678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/media\/2671"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/media?parent=2666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/categories?post=2666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/es\/wp-json\/wp\/v2\/tags?post=2666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}