{"id":2481,"date":"2024-08-26T15:29:47","date_gmt":"2024-08-26T13:29:47","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2481"},"modified":"2024-08-26T15:29:48","modified_gmt":"2024-08-26T13:29:48","slug":"anderson-silva-la-sua-storia-altezza-peso-eta-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/","title":{"rendered":"Anderson Silva: storia, altezza, peso, et\u00e0, patrimonio"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Breve riassunto dell'articolo<\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Oggetto<\/strong><\/th><th><strong>Dettagli<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Nome<\/strong><\/td><td>Anderson Silva<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-taille\/\">Dimensione<\/a><\/strong><\/td><td>1m88<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong><\/td><td>84 kg<\/td><\/tr><tr><td><strong>Et\u00e0<\/strong><\/td><td>49 anni (nato il 14 aprile 1975)<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-fortune\/\">La Fortuna<\/a> stimato<\/strong><\/td><td>18 milioni di euro<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h3 class=\"wp-block-heading\">Introduzione<\/h3>\n\n\n\n<p>Nel mondo delle arti marziali miste, ci sono nomi che rimangono impressi nella memoria collettiva degli appassionati, nomi che vanno ben oltre le semplici statistiche o i record. Anderson Silva \u00e8 uno di questi nomi che ha trasceso lo sport per diventare una vera e propria leggenda. Quando parliamo di Silva, non parliamo solo di un lottatore eccezionale, ma di un artista, uno stratega e un innovatore che ha ridefinito il significato di salire nell'ottagono. Dalle sue umili origini a San Paolo al suo regno ininterrotto nell'UFC, Silva \u00e8 sempre stato pi\u00f9 di un semplice atleta. Egli incarna l'essenza stessa delle MMA: la combinazione di tecnica, spirito combattivo e audacia. Preparatevi quindi ad approfondire l'affascinante storia di colui che chiamano \"Il Ragno\" e a scoprire come ha lasciato il segno nella storia di questo sport.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Anderson Silva: storia, altezza, peso, et\u00e0, patrimonio<\/h2>\n\n\n\n<p>Anderson Silva \u00e8 un nome che risuona nel mondo delle MMA come quello di un titano. Nato il 14 aprile 1975 nei modesti quartieri di San Paolo, in Brasile, Silva \u00e8 cresciuto in un ambiente in cui le opportunit\u00e0 erano limitate. Fin da piccolo \u00e8 stato attratto dalle arti marziali, prima dal Taekwondo, poi dalla Muay Thai e dal jiu-jitsu brasiliano. La sua altezza di 1 metro e 88 gli ha dato rapidamente un vantaggio naturale negli sport da combattimento, permettendogli di usare il suo raggio d'azione per neutralizzare gli avversari. Ma non \u00e8 solo una questione di fisico: Silva \u00e8 sempre stato un tecnico eccezionale. Al peso competitivo di 84 kg, si muoveva nell'ottagono con una fluidit\u00e0 e una grazia raramente viste a questo livello di competizione.<\/p>\n\n\n\n<p>Silva ha debuttato nelle MMA nel 1997 e non ci \u00e8 voluto molto perch\u00e9 il suo talento venisse riconosciuto. Nel corso degli anni ha combattuto in diverse organizzazioni prima di entrare nell'UFC nel 2006, dove ha rapidamente scolpito il suo nome nella pietra. Il suo successo non si misura solo in vittorie, ma anche in termini di riconoscimento mondiale e di ricchezza accumulata. Oggi il suo patrimonio \u00e8 stimato in circa 18 milioni di dollari. Questa cifra testimonia non solo la sua bravura nell'ottagono, ma anche la sua capacit\u00e0 di monetizzare la sua carriera attraverso contratti pubblicitari, partnership e investimenti oculati. Al di l\u00e0 dei soldi, sono il rispetto e l'ammirazione che suscita a testimoniare il suo impatto sullo sport.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una carriera impressionante nelle MMA<\/h3>\n\n\n\n<p>Il viaggio di Anderson Silva nelle MMA \u00e8 una favola moderna. Quello che \u00e8 iniziato come una semplice passione per le arti marziali si \u00e8 trasformato in una carriera leggendaria che ha ridefinito le norme di questo sport. Da umili inizi nelle competizioni locali in Brasile, Silva ha iniziato a farsi un nome sulla scena internazionale grazie alle sue impressionanti performance. Ha combattuto in diverse organizzazioni, tra cui Pride FC e Cage Rage, prima di fare il salto nell'UFC, il pi\u00f9 grande palcoscenico delle MMA, nel 2006.<\/p>\n\n\n\n<p>Appena arrivato nell'UFC, Silva ha dimostrato di essere un combattente a parte. Vince il suo primo incontro contro Chris Leben in soli 49 secondi, attirando immediatamente l'attenzione del mondo. Poco dopo affront\u00f2 l'allora campione dei pesi medi Rich Franklin, che batt\u00e9 in modo decisivo per vincere il titolo. Questo fu solo l'inizio di quello che sarebbe diventato uno dei pi\u00f9 lunghi periodi di dominio nella storia dell'UFC. Silva ha difeso il titolo dei pesi medi per dieci volte, un record tuttora imbattuto.<\/p>\n\n\n\n<p>Ma non \u00e8 stato solo il numero di vittorie a impressionare, bens\u00ec il modo in cui le ha ottenute. Silva aveva una capacit\u00e0 unica di analizzare i suoi avversari, di farli crollare mentalmente e di batterli con precisione chirurgica. I suoi combattimenti sono stati spesso paragonati a opere d'arte, in cui ogni mossa era calcolata, ogni colpo sferrato con notevole intento e finezza. Questo periodo di dominio ha reso Silva non solo un campione, ma una vera e propria icona di questo sport.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lo stile di combattimento unico di Anderson Silva<\/h3>\n\n\n\n<p>Anderson Silva non era solo un lottatore, era un virtuoso dell'ottagono. Il suo stile di combattimento, imprevedibile e metodico al tempo stesso, lo rendeva un incubo per i suoi avversari. Uno degli aspetti pi\u00f9 affascinanti del suo stile era la capacit\u00e0 di usare la sua stazza e il suo allungo per tenere gli avversari a distanza, pur riuscendo a colpirli con una precisione devastante. I suoi calci, in particolare, erano leggendari, capaci di mettere al tappeto un avversario in un istante, come dimostr\u00f2 con il suo spettacolare front kick contro Vitor Belfort.<\/p>\n\n\n\n<p>Ma ci\u00f2 che distingueva Silva era il suo movimento. Si muoveva nell'ottagono come un ballerino, schivando i colpi con una facilit\u00e0 quasi soprannaturale. Aveva un modo di frustrare i suoi avversari, inducendoli a commettere errori che lui sfruttava immediatamente. Silva aveva una comprensione unica del tempismo e della distanza, che gli permetteva di colpire i suoi avversari dove erano pi\u00f9 vulnerabili. Questo stile non solo lo ha reso un campione, ma ha anche reinventato il significato di essere un lottatore nell'UFC.<\/p>\n\n\n\n<p>Silva era anche un esperto di jiu-jitsu brasiliano, un'abilit\u00e0 che non esitava a usare quando il combattimento era a terra. Sebbene le sue abilit\u00e0 nella lotta in piedi fossero spesso evidenziate, il suo lavoro a terra era altrettanto impressionante. Sapeva come controllare i suoi avversari, sottometterli o neutralizzarli, rendendolo un combattente completo. Questa miscela unica di tecniche in piedi e a terra lo ha reso un vero e proprio pioniere delle MMA, un lottatore in grado di fare tutto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I punti salienti della carriera<\/h3>\n\n\n\n<p>La carriera di Anderson Silva \u00e8 costellata di momenti che hanno lasciato il segno nella storia delle MMA, ognuno dei quali ha contribuito a forgiare la sua leggenda. Uno dei momenti pi\u00f9 iconici della sua carriera \u00e8 senza dubbio lo spettacolare KO contro Vitor Belfort nel 2011. Quel calcio frontale \u00e8 diventato una delle immagini pi\u00f9 iconiche dell'UFC, spuntando dal nulla per mettere al tappeto Belfort e ricordare a tutti perch\u00e9 Silva era considerato uno dei pi\u00f9 grandi di tutti i tempi. Quell'incontro non fu solo una vittoria, ma una dimostrazione del suo genio tattico e della sua capacit\u00e0 di innovare anche all'apice della sua carriera.<\/p>\n\n\n\n<p>Un altro momento chiave della sua carriera \u00e8 stata la prima vittoria su Rich Franklin nel 2006, che gli \u00e8 valsa il titolo dei pesi medi UFC. All'epoca Franklin era considerato uno dei migliori del settore, ma Silva lo smantell\u00f2 con precisione clinica. La vittoria ha segnato l'inizio del suo regno di sette anni come campione, durante i quali ha affrontato e battuto alcuni dei pi\u00f9 grandi nomi di questo sport, da Dan Henderson a Chael Sonnen.<\/p>\n\n\n\n<p>E naturalmente c'\u00e8 stata la sua striscia vincente da record di 16 incontri nell'UFC. Quella serie ha cementato il suo posto tra i grandi, non solo per la durata del suo dominio, ma anche per il modo in cui ha vinto quegli incontri. Ogni vittoria \u00e8 stata unica, ogni prestazione ha portato qualcosa di nuovo. Silva non ha solo vinto, ha reinventato lo sport ogni volta che \u00e8 entrato nell'ottagono. Questi momenti salienti non sono solo ricordi per gli appassionati di MMA, ma sono pietre miliari nella storia di questo sport.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La fortuna di Anderson Silva<\/h2>\n\n\n\n<p>Anderson Silva non \u00e8 solo un campione nell'ottagono, ma anche un accorto uomo d'affari. Con una carriera di tale successo, non sorprende che sia riuscito ad accumulare una notevole fortuna nel corso degli anni. Il suo patrimonio \u00e8 stimato intorno ai 18 milioni di dollari, una cifra che riflette non solo i suoi guadagni nelle MMA, ma anche i numerosi contratti di sponsorizzazione e gli investimenti intelligenti. Silva ha sfruttato la sua immagine e la sua fama mondiale per firmare contratti lucrativi con marchi internazionali, rendendolo uno degli atleti pi\u00f9 redditizi di questo sport.<\/p>\n\n\n\n<p>Oltre ai guadagni diretti derivanti dai combattimenti, Silva ha anche diversificato le sue fonti di reddito. Ha investito in aziende, ha partecipato a <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/films-avec-mike-tyson\/\">film<\/a> e ha persino lanciato la sua linea di abbigliamento. \u00c8 stato anche uno dei primi lottatori di MMA a capire l'importanza di costruire un marchio personale, che gli ha permesso di rimanere rilevante e visibile anche dopo aver lasciato l'ottagono. Silva ha trasformato il suo successo sportivo in una fortuna finanziaria, assicurando la stabilit\u00e0 sua e della sua famiglia per gli anni a venire.<\/p>\n\n\n\n<p>Ma al di l\u00e0 del denaro, ci\u00f2 che distingue Silva \u00e8 il suo impegno per le cause che gli stanno a cuore. Ha utilizzato la sua fortuna per sostenere una serie di enti di beneficenza, in particolare quelli che si occupano di disabili. <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-enfants\/\">bambini<\/a> in Brasile. Silva \u00e8 rimasto fedele alle sue radici, sfruttando il suo successo per dare un contributo alla comunit\u00e0 in cui \u00e8 cresciuto. Questo impegno sociale dimostra che Silva non \u00e8 solo un lottatore eccezionale, ma anche un uomo dal cuore grande, consapevole dell'impatto che pu\u00f2 avere al di fuori dello sport.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anderson Silva oggi<\/h3>\n\n\n\n<p>A 49 anni, Anderson Silva continua a sfidare le aspettative. Sebbene si sia ufficialmente ritirato dalle MMA nel 2020, il \"Ragno\" non ha mai abbandonato il mondo degli sport da combattimento. Di recente ha fatto un notevole ritorno, questa volta nel mondo della boxe. Il suo ritorno non \u00e8 passato inosservato. Silva ha gi\u00e0 ottenuto una serie di vittorie, dimostrando di possedere ancora capacit\u00e0 eccezionali nonostante l'et\u00e0. Il suo passaggio alla boxe dimostra che, anche dopo una carriera cos\u00ec lunga e ricca di successi, ha ancora sete di competizione e voglia di mettersi alla prova con nuove sfide.<\/p>\n\n\n\n<p>Ma Anderson Silva non \u00e8 solo un lottatore. \u00c8 anche un mentore, un modello per la nuova generazione di lottatori. Molti giovani atleti guardano a lui come fonte di ispirazione e Silva non esita a condividere con loro la sua esperienza e i suoi consigli. Viene regolarmente invitato a seminari e conferenze, dove parla della sua carriera, delle sue strategie e del suo stato d'animo. Silva continua ad avere un impatto significativo su questo sport, anche al di fuori dell'ottagono.<\/p>\n\n\n\n<p>Allo stesso tempo, Silva \u00e8 anche molto attivo nella filantropia. Sostiene diverse iniziative a favore dei bambini svantaggiati, soprattutto in Brasile, dove rimane una figura emblematica. Utilizza la sua fama per attirare l'attenzione su cause importanti e per mobilitare risorse a favore di chi ne ha bisogno. In breve, Anderson Silva \u00e8 molto pi\u00f9 di un ex campione di MMA: \u00e8 un'icona, un leader e un uomo profondamente impegnato per gli altri.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conclusione<\/h4>\n\n\n\n<p>Anderson Silva non \u00e8 solo un altro nome nella storia delle MMA, \u00e8 una leggenda vivente. Dalle sue umili origini a San Paolo alla sua ascesa ai vertici del mondo delle MMA, Silva si \u00e8 sempre distinto per talento, carisma e determinazione. Con una carriera costellata di momenti indimenticabili, uno stile di combattimento unico e una fortuna meritata, ha lasciato un segno indelebile in questo sport. E anche dopo aver appeso i guantoni al chiodo, continua a ispirare e motivare le nuove generazioni, impegnandosi al contempo in cause che gli stanno a cuore. Anderson Silva \u00e8 la storia di un uomo che ha trasformato i suoi sogni in realt\u00e0, rimanendo fedele ai suoi valori e alle sue radici. Una vera leggenda e un esempio da seguire per tutti.<\/p>\n\n\n\n<p>Fonti : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4814\">Boxe Wiki <\/a><\/strong><\/p>\n\n\n\n<p>Vedi anche :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4815\"> Sito ufficiale dei veterani<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Breve riassunto dell'articolo in breve Dettagli del soggetto Nome Anderson Silva Altezza 1m88 Peso 84 kg Et\u00e0 49 (nato il 14 aprile 1975) Patrimonio stimato 18 milioni di dollari Introduzione Nel mondo delle arti marziali miste, ci sono alcuni nomi che sono impressi nella memoria collettiva ... <a title=\"Anderson Silva: storia, altezza, peso, et\u00e0, patrimonio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/\" aria-label=\"Per saperne di pi\u00f9 su Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune\">Leggi tutto<\/a><\/p>","protected":false},"author":2,"featured_media":2483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Anderson Silva, c&#039;est un nom qui fait vibrer les fans de MMA. N\u00e9 le 14 avril 1975 \u00e0 S\u00e3o Paulo, au Br\u00e9sil, il a grandi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Anderson Silva, c&#039;est un nom qui fait vibrer les fans de MMA. N\u00e9 le 14 avril 1975 \u00e0 S\u00e3o Paulo, au Br\u00e9sil, il a grandi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-26T13:29:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T13:29:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/08\/SILVA_ANDERSON_10-31-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"520\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-08-26T13:29:47+00:00\",\"dateModified\":\"2024-08-26T13:29:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/\"},\"wordCount\":2271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SILVA_ANDERSON_10-31-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/\",\"name\":\"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SILVA_ANDERSON_10-31-removebg-preview.png\",\"datePublished\":\"2024-08-26T13:29:47+00:00\",\"dateModified\":\"2024-08-26T13:29:48+00:00\",\"description\":\"Anderson Silva, c'est un nom qui fait vibrer les fans de MMA. N\u00e9 le 14 avril 1975 \u00e0 S\u00e3o Paulo, au Br\u00e9sil, il a grandi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SILVA_ANDERSON_10-31-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/SILVA_ANDERSON_10-31-removebg-preview.png\",\"width\":520,\"height\":325,\"caption\":\"Anderson Silva\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/anderson-silva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anderson Silva: storia, altezza, peso, et\u00e0, patrimonio","description":"Anderson Silva \u00e8 un nome che entusiasma gli appassionati di MMA. Nato il 14 aprile 1975 a S\u00e3o Paulo, in Brasile, \u00e8 cresciuto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/","og_locale":"it_IT","og_type":"article","og_title":"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Anderson Silva, c'est un nom qui fait vibrer les fans de MMA. N\u00e9 le 14 avril 1975 \u00e0 S\u00e3o Paulo, au Br\u00e9sil, il a grandi","og_url":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/","og_site_name":"Boxeur PRO","article_published_time":"2024-08-26T13:29:47+00:00","article_modified_time":"2024-08-26T13:29:48+00:00","og_image":[{"width":520,"height":325,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/08\/SILVA_ANDERSON_10-31-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maxime","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-08-26T13:29:47+00:00","dateModified":"2024-08-26T13:29:48+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/"},"wordCount":2271,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/08\/SILVA_ANDERSON_10-31-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/","url":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/","name":"Anderson Silva: storia, altezza, peso, et\u00e0, patrimonio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/08\/SILVA_ANDERSON_10-31-removebg-preview.png","datePublished":"2024-08-26T13:29:47+00:00","dateModified":"2024-08-26T13:29:48+00:00","description":"Anderson Silva \u00e8 un nome che entusiasma gli appassionati di MMA. Nato il 14 aprile 1975 a S\u00e3o Paulo, in Brasile, \u00e8 cresciuto","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/it\/anderson-silva\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/08\/SILVA_ANDERSON_10-31-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/08\/SILVA_ANDERSON_10-31-removebg-preview.png","width":520,"height":325,"caption":"Anderson Silva"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/it\/anderson-silva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Anderson Silva : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/it\/#website","url":"https:\/\/boxeur-pro.fr\/it\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/it\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/it\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/2481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/comments?post=2481"}],"version-history":[{"count":2,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/2481\/revisions"}],"predecessor-version":[{"id":2484,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/2481\/revisions\/2484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/media\/2483"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/media?parent=2481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/categories?post=2481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/tags?post=2481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}