{"id":2616,"date":"2024-09-12T18:07:36","date_gmt":"2024-09-12T16:07:36","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2616"},"modified":"2024-09-12T18:08:28","modified_gmt":"2024-09-12T16:08:28","slug":"colby-covington-la-sua-storia-altezza-peso-eta-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/","title":{"rendered":"Colby Covington: storia, altezza, peso, et\u00e0, patrimonio"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Rapido riassunto dell'articolo:<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Colby Covington<\/strong><\/th><th><strong>Et\u00e0<\/strong> 35 anni<\/th><\/tr><\/thead><tbody><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-taille\/\">Dimensione<\/a><\/strong> : 1m80<\/td><td><strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong> Peso: 77 kg<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-fortune\/\">La Fortuna<\/a><\/strong> 2 milioni di dollari<\/td><td><strong>Titolo<\/strong> Ex campione UFC ad interim<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Introduzione<\/h3>\n\n\n\n<p>Colby Covington \u00e8 un nome che anche chi non segue da vicino le MMA conosce. E perch\u00e9? Perch\u00e9 non fa le cose a met\u00e0. \u00c8 l\u00ec per scioccare, per brillare, per far parlare di s\u00e9, sia per i suoi combattimenti che per le sue dichiarazioni. Lo si pu\u00f2 odiare o ammirare, ma non lascia nessuno indifferente. In un mondo in cui il combattimento \u00e8 anche spettacolo, Covington si \u00e8 creato un posto giocando con i codici. Ma non dobbiamo dimenticare che dietro tutto questo clamore mediatico si nasconde un atleta formidabile, un vero guerriero dell'ottagono.<\/p>\n\n\n\n<p>Il ragazzo ha un curriculum impressionante e una resistenza mozzafiato. Se lo vedete parlare molto, non fatevi illusioni: pu\u00f2 anche combattere senza tregua per cinque round. C'\u00e8 un motivo se ha scalato la scala dell'UFC. Ma per capire veramente chi \u00e8 Colby Covington, bisogna tornare agli esordi, dove tutto \u00e8 cominciato per questo showman che \u00e8 diventato una delle figure pi\u00f9 controverse delle MMA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Colby Covington: una storia degna di un film<\/h2>\n\n\n\n<p>La storia di Colby Covington \u00e8 iniziata lontano dalle luci della ribalta. Nato in California, si trasferisce presto con la famiglia in Oregon, un luogo molto pi\u00f9 tranquillo. \u00c8 l\u00ec che scopre la passione per il wrestling, uno sport che definir\u00e0 la sua vita e la sua carriera. A scuola, Colby non passava inosservato. Era noto per la sua tenacia e il suo desiderio di essere sempre il migliore. Semplicemente, odiava perdere, sia sul tappeto di lotta che altrove. Questa mentalit\u00e0 lo accompagner\u00e0 per tutta la sua carriera.<\/p>\n\n\n\n<p>A livello universitario, \u00e8 diventato una vera e propria star del wrestling. Ha vinto campionati, si \u00e8 fatto un nome tra i migliori lottatori del Paese, e a quel punto si \u00e8 detto: \"Perch\u00e9 non tentare la fortuna nelle MMA? E poi le cose hanno preso una piega spettacolare. L'ingresso di Covington nelle MMA \u00e8 stato segnato da uno stile di lotta molto dominante. Ma sapeva che per avere successo in questo sport bisognava anche crearsi un'immagine, un personaggio che catturasse i fan e attirasse i riflettori. Cos\u00ec ha creato una personalit\u00e0 provocatoria, adottando un atteggiamento da \"cattivo ragazzo\" che avrebbe cambiato la sua intera carriera.<\/p>\n\n\n\n<p>Ci\u00f2 che affascina \u00e8 la misura in cui \u00e8 riuscito a manipolare la sua immagine. Non si \u00e8 trattato di un semplice colpo di fortuna, ma di una strategia attentamente studiata. Diventando il nemico pubblico numero uno, \u00e8 riuscito ad attirare l'attenzione dei media, dei fan e persino dei suoi avversari. E ha funzionato. In pochi anni \u00e8 diventato uno dei lottatori pi\u00f9 popolari (e controversi) dell'UFC. Alcuni sostengono che senza questo personaggio non avrebbe mai raggiunto questo livello. Ma una cosa \u00e8 certa: Colby \u00e8 un convinto sostenitore.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dimensioni e peso: la macchina Covington<\/h3>\n\n\n\n<p>1m80 per 77 kg, queste sono le cifre di Colby Covington. Ma non lasciatevi ingannare da queste statistiche. Ci\u00f2 che rende Colby pericoloso non \u00e8 solo la sua altezza o il suo peso, ma tutto ci\u00f2 che c'\u00e8 dietro. Covington \u00e8 un pugile a s\u00e9 stante, perch\u00e9 la sua vera risorsa \u00e8 la sua fenomenale resistenza. Dove gli altri rallentano, lui accelera. Ti spinge al limite, ti fa correre in tutte le direzioni e a un certo punto crolli. \u00c8 una strategia che ha perfezionato nel corso degli anni.<\/p>\n\n\n\n<p>La sua lotta \u00e8 ovviamente la sua base. Colby sa come mantenere la pressione, come portarti a terra e stancarti. Ma ci\u00f2 che lo distingue dagli altri lottatori \u00e8 il suo volume di colpi. Questo ragazzo non smette mai di colpire. Anche quando si pensa che stia per rallentare, continua a colpire, senza tregua. Non sono molti i lottatori che riescono a tenere il suo passo. Ecco perch\u00e9 \u00e8 riuscito a dominare avversari fisicamente pi\u00f9 grandi di lui.<\/p>\n\n\n\n<p>Dobbiamo anche parlare del suo stato mentale. Non crolla mai, indipendentemente dalla situazione in cui si trova. Nel suo primo incontro contro Kamaru Usman, si \u00e8 letteralmente rotto la mascella durante il combattimento. Chiunque altro si sarebbe arreso. Ma non Covington. Ha continuato a combattere fino alla fine, dimostrando una straordinaria capacit\u00e0 di recupero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Et\u00e0 e carriera: 35 anni e ancora al top<\/h3>\n\n\n\n<p>A 35 anni, alcuni pugili iniziano a pensare al ritiro, ma non Colby Covington. \u00c8 ancora in gioco. \u00c8 ancora tra i primi 5 pesi welter e non ha intenzione di fermarsi presto. E perch\u00e9? Perch\u00e9 \u00e8 fermamente convinto di poter diventare di nuovo campione e nulla sembra fermarlo. \u00c8 gi\u00e0 stato campione UFC ad interim, ma il suo obiettivo finale resta quello di conquistare la cintura ufficiale.<\/p>\n\n\n\n<p>Ci\u00f2 che \u00e8 notevole di lui \u00e8 la sua capacit\u00e0 di reinventarsi. Ogni volta che combatte, mostra qualcosa di nuovo. Che si tratti della sua tecnica, del suo approccio o della sua mentalit\u00e0. Non si adagia mai sugli allori. \u00c8 un perfezionista. E anche se ha gi\u00e0 raggiunto un certo livello di successo, continua ad allenarsi con un'intensit\u00e0 pazzesca, come se ogni incontro fosse il pi\u00f9 importante della sua carriera.<\/p>\n\n\n\n<p>Mentre gli altri si adagiano sugli allori, Colby si spinge sempre oltre. Non ha paura di mettere in gioco il suo titolo, di rischiare o addirittura di allontanare tutti. La sua et\u00e0 non lo rallenta. Anzi, usa la sua esperienza per diventare ancora pi\u00f9 temibile. Ed \u00e8 questo che lo rende un avversario terribilmente pericoloso per chiunque nella divisione dei pesi welter.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La sua fortuna: tra scontri e provocazioni<\/h3>\n\n\n\n<p>Con tutto il rumore che sta facendo, si potrebbe pensare che Colby Covington sia multimilionario. Eppure il suo patrimonio \u00e8 stimato intorno ai 2 milioni di dollari, una cifra relativamente modesta rispetto ad altre star dell'UFC. Come si spiega questa situazione? In realt\u00e0, Colby non \u00e8 mai stato il lottatore pi\u00f9 pagato, pur essendo una figura importante dell'organizzazione. Il motivo \u00e8 semplice: ha sempre privilegiato l'incontro rispetto alla promozione. Ma questo prima di trasformarsi in Chaos.<\/p>\n\n\n\n<p>Oggi Colby non si accontenta pi\u00f9 di combattere. Sa che per incrementare il suo conto in banca \u00e8 necessario anche giocare con i media. Cos\u00ec ha aumentato le sue apparizioni, ha firmato contratti di sponsorizzazione e, soprattutto, si \u00e8 reso indispensabile per l'UFC. Anche se le sue provocazioni non piacciono a tutti, generano un pubblico, ed \u00e8 questo che l'UFC sta cercando. Ogni dichiarazione, ogni tweet \u00e8 un modo per rimanere rilevante, anche quando non ha un incontro in programma.<\/p>\n\n\n\n<p>Il suo carattere da cattivo lo ha anche aiutato a ottenere bonus di combattimento. Colby sa come vendere i suoi incontri. Sa che i fan amano le rivalit\u00e0 e le tensioni e non esita a metterle in risalto. Ogni volta che entra nell'ottagono, si assicura che i riflettori siano puntati su di lui. Anche se non ha la fortuna di Conor McGregor, \u00e8 sulla buona strada per diventare uno dei pugili pi\u00f9 redditizi della sua categoria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le sue rivalit\u00e0: una storia di caos<\/h2>\n\n\n\n<p>Colby Covington e le rivalit\u00e0 hanno una lunga storia di amore (o meglio di odio). Se seguite l'UFC, saprete che questo ragazzo non entra nell'ottagono solo per combattere. No, deve scaldare gli animi prima, durante e anche dopo l'incontro. Che si tratti di Kamaru Usman, Tyron Woodley o del suo ex migliore amico Jorge Masvidal, Colby non ha mai avuto paura di gettare benzina sul fuoco.<\/p>\n\n\n\n<p>Il suo linguaggio trash \u00e8 leggendario e sa esattamente come colpire nel segno. A volte \u00e8 cos\u00ec estremo che ci si chiede se sia tutto programmato. Ma no, Colby \u00e8<\/p>\n\n\n\n<p>autentico. Dice quello che pensa e lo dice brutalmente. Non esita ad attaccare sul piano personale, a provocare, a umiliare i suoi avversari prima ancora di salire sul ring.<\/p>\n\n\n\n<p>L'incontro contro Kamaru Usman, ad esempio, \u00e8 stato pi\u00f9 di una semplice battaglia per il titolo dei pesi welter. \u00c8 stata una guerra psicologica. Colby ha trascorso mesi a provocare Usman, facendogli perdere l'equilibrio. Anche se Covington ha perso l'incontro, la rivalit\u00e0 tra i due \u00e8 rimasta intensa. E con Masvidal \u00e8 ancora pi\u00f9 personale. Un tempo i due erano inseparabili e condividevano tutto, dall'allenamento al relax. Ora sono diventati nemici giurati e il loro scontro \u00e8 stato uno dei pi\u00f9 attesi della storia recente dell'UFC.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I suoi punti di forza nell'ottagono<\/h3>\n\n\n\n<p>Parliamo un po' di tecnica. Il punto di forza di Colby Covington non \u00e8 solo il suo straordinario cardio (anche se questo aiuta molto). \u00c8 il suo stile di combattimento unico, che mescola lotta di alto livello e colpi ad alto volume. In pratica, ti sfinisce facendoti correre in tutte le direzioni e, mentre tu stai boccheggiando, lui continua a colpire senza sosta. Semplicemente, non ti d\u00e0 tregua.<\/p>\n\n\n\n<p>La lotta \u00e8, ovviamente, la sua arma principale. Pochi lottatori possono competere con lui in questo campo. Ti afferra, ti sbatte a terra e poi ti blocca. Ma il suo punto di forza \u00e8 la capacit\u00e0 di combinare la lotta con un'impressionante quantit\u00e0 di colpi. Non \u00e8 un lottatore che cerca necessariamente il KO, ma ci arriva. <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/meilleur-sac-de-frappe-boxe\/\">colpito<\/a> cos\u00ec spesso che si finisce per crollare.<\/p>\n\n\n\n<p>Un altro punto di forza \u00e8 la sua capacit\u00e0 di mantenere la pressione. Colby non d\u00e0 mai ai suoi avversari il tempo di respirare. Non appena suona la campana, si avventa su di te e non si ferma fino alla fine del round. Non importa se sei pi\u00f9 grosso, pi\u00f9 pesante o pi\u00f9 forte. Se non hai un sistema cardio degno dei Giochi Olimpici, soffrirai contro di lui. La sua capacit\u00e0 di sfiancare gli avversari lo rende uno dei pugili pi\u00f9 temuti della categoria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La sua personalit\u00e0 fuori dal ring<\/h3>\n\n\n\n<p>Fuori dall'ottagono, Colby Covington \u00e8 altrettanto provocatorio, se non di pi\u00f9. Ha un'opinione su tutto, soprattutto su questioni divisive. In particolare, ha dichiarato apertamente il suo sostegno a Donald Trump, il che gli \u00e8 valso molte critiche, ma anche la popolarit\u00e0 di una certa frangia del pubblico americano. Covington sa che ogni affermazione fa rumore e non esita a giocarci sopra.<\/p>\n\n\n\n<p>Ma dietro questa facciata provocatoria, alcuni sostengono che Colby sia in realt\u00e0 una persona molto riflessiva e calcolatrice. Sa che nel mondo delle MMA bisogna vendersi per esistere e conosce perfettamente le regole del gioco. Ogni parola, ogni apparizione sui media \u00e8 pianificata meticolosamente per attirare l'attenzione. E anche se questo a volte lo mette nei guai, \u00e8 anche ci\u00f2 che lo rende cos\u00ec affascinante. \u00c8 impossibile ignorarlo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conclusione<\/h4>\n\n\n\n<p>Colby Covington \u00e8 un combattente straordinario, sia fisicamente che mentalmente. La sua carriera \u00e8 stata costellata da rivalit\u00e0 esplosive, combattimenti intensi e dalla capacit\u00e0 di rialzarsi sempre, a prescindere dagli ostacoli. Che lo si ammiri o lo si odi, una cosa \u00e8 certa: \u00e8 impegnato a lungo e ha ancora molte sfide davanti a s\u00e9. A 35 anni non ha ancora detto la sua ultima parola e se pensate di aver visto abbastanza di \"Chaos\", aspettatevi di essere sorpresi.<\/p>\n\n\n\n<p>Fonti : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4909\">Boxe Wiki <\/a><\/strong><\/p>\n\n\n\n<p>Vedi anche :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4910\"> Sito ufficiale dei veterani<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Riassunto dell'articolo in breve: Colby Covington Et\u00e0: 35 Altezza: 1m80 Peso: 77 kg Patrimonio: 2 milioni di dollari Titolo: Ex campione ad interim UFC Introduzione Colby Covington \u00e8 un nome che anche chi non segue da vicino le MMA conoscer\u00e0. Ma perch\u00e9? <a title=\"Colby Covington: storia, altezza, peso, et\u00e0, patrimonio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/it\/colby-covington\/\" aria-label=\"Per saperne di pi\u00f9 su Colby Covington : son histoire, taille, poids, \u00e2ge, fortune\">Leggi tutto<\/a><\/p>","protected":false},"author":2,"featured_media":2610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colby Covington : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Colby Covington est un combattant hors du commun, \u00e0 la fois sur le plan physique et mental. Sa carri\u00e8re est jalonn\u00e9e de rivalit\u00e9s explosives\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/it\/colby-covington\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Colby Covington est un combattant hors du commun, \u00e0 la fois sur le plan physique et mental. Sa carri\u00e8re est jalonn\u00e9e de rivalit\u00e9s explosives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/it\/colby-covington\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T16:07:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T16:08:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3088810-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-09-12T16:07:36+00:00\",\"dateModified\":\"2024-09-12T16:08:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/\"},\"wordCount\":2194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3088810-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/\",\"name\":\"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3088810-removebg-preview.png\",\"datePublished\":\"2024-09-12T16:07:36+00:00\",\"dateModified\":\"2024-09-12T16:08:28+00:00\",\"description\":\"Colby Covington est un combattant hors du commun, \u00e0 la fois sur le plan physique et mental. Sa carri\u00e8re est jalonn\u00e9e de rivalit\u00e9s explosives\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3088810-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3088810-removebg-preview.png\",\"width\":586,\"height\":426,\"caption\":\"Colby Covington\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/colby-covington\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colby Covington: storia, altezza, peso, et\u00e0, patrimonio","description":"Colby Covington \u00e8 un combattente straordinario, sia fisicamente che mentalmente. La sua carriera \u00e8 stata costellata da rivalit\u00e0 esplosive.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/","og_locale":"it_IT","og_type":"article","og_title":"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Colby Covington est un combattant hors du commun, \u00e0 la fois sur le plan physique et mental. Sa carri\u00e8re est jalonn\u00e9e de rivalit\u00e9s explosives","og_url":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/","og_site_name":"Boxeur PRO","article_published_time":"2024-09-12T16:07:36+00:00","article_modified_time":"2024-09-12T16:08:28+00:00","og_image":[{"width":586,"height":426,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3088810-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maxime","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-09-12T16:07:36+00:00","dateModified":"2024-09-12T16:08:28+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/"},"wordCount":2194,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3088810-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/it\/colby-covington\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/","url":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/","name":"Colby Covington: storia, altezza, peso, et\u00e0, patrimonio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3088810-removebg-preview.png","datePublished":"2024-09-12T16:07:36+00:00","dateModified":"2024-09-12T16:08:28+00:00","description":"Colby Covington \u00e8 un combattente straordinario, sia fisicamente che mentalmente. La sua carriera \u00e8 stata costellata da rivalit\u00e0 esplosive.","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/it\/colby-covington\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3088810-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3088810-removebg-preview.png","width":586,"height":426,"caption":"Colby Covington"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/it\/colby-covington\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Colby Covington : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/it\/#website","url":"https:\/\/boxeur-pro.fr\/it\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/it\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/it\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/2616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/comments?post=2616"}],"version-history":[{"count":2,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/2616\/revisions"}],"predecessor-version":[{"id":2618,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/2616\/revisions\/2618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/media\/2610"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/media?parent=2616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/categories?post=2616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/tags?post=2616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}