{"id":3215,"date":"2024-12-16T17:56:00","date_gmt":"2024-12-16T16:56:00","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=3215"},"modified":"2024-12-16T19:06:49","modified_gmt":"2024-12-16T18:06:49","slug":"petzl-swift-rl-900-lumens-avis-lampe-frontale","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/","title":{"rendered":"Petzl Swift RL - 900 lumen: recensione della lampada frontale"},"content":{"rendered":"<affilizz-rendering-component loading=\"lazy\" publication-content-id=\"676068af30999b4329a6265e\"><\/affilizz-rendering-component>\n\n\n\n<p>Salut les amis ! Aujourd&rsquo;hui, on va parler d&rsquo;un \u00e9quipement qui va illuminer vos sessions d&rsquo;entra\u00eenement nocturnes. Eh oui, m\u00eame nous les boxeurs, on a parfois besoin d&rsquo;un peu de lumi\u00e8re pour voir o\u00f9 on met les pieds. Alors, attachez vos gants, on va \u00e9tudier ensemble la Petzl Swift RL &#8211; 900 lumens !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Introduction \u00e0 la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<p>Quand j&rsquo;ai commenc\u00e9 \u00e0 m&rsquo;entra\u00eener t\u00f4t le matin et tard le soir, j&rsquo;ai vite compris qu&rsquo;une bonne lampe frontale \u00e9tait aussi indispensable que mes <a href=\"https:\/\/boxeur-pro.fr\/it\/blog\/confronto-tra-i-migliori-orologi-sportivi-connessi\/\" data-lasso-id=\"5740\">meilleures montres connect\u00e9es pour le sport<\/a>. La Petzl Swift RL &#8211; 900 lumens m&rsquo;a tap\u00e9 dans l&rsquo;\u0153il avec sa puissance impressionnante et son design futuriste. C&rsquo;est comme avoir un mini-soleil attach\u00e9 \u00e0 votre <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/meilleur-casque-de-boxe\/\">testa<\/a>, sans le risque de coup de soleil !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notre avis sur la Petzl Swift RL &#8211; 900 lumens<\/h2>\n\n\n\n<affilizz-rendering-component loading=\"lazy\" publication-content-id=\"676068af30999b4329a6265f\"><\/affilizz-rendering-component>\n\n\n\n<h3 class=\"wp-block-heading\">Comment fonctionne la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<p>Cette petite merveille fonctionne avec deux modes d&rsquo;\u00e9clairage : le Standard Lighting et le Reactive Lighting. Le mode Reactive, c&rsquo;est un peu comme avoir un assistant personnel qui ajuste la lumi\u00e8re pour vous. Gr\u00e2ce \u00e0 un capteur de luminosit\u00e9 int\u00e9gr\u00e9, la lampe adapte automatiquement sa puissance. Plus besoin de tripoter les boutons en plein sprint !<\/p>\n\n\n\n<p>Avec ses deux faisceaux int\u00e9gr\u00e9s, large et mixte, cette lampe offre une visibilit\u00e9 optimale jusqu&rsquo;\u00e0 150 m\u00e8tres. C&rsquo;est comme si vous aviez des yeux de chat, mais en mieux ! Et le tout avec une autonomie qui peut aller jusqu&rsquo;\u00e0 100 heures. De quoi tenir pendant vos sessions d&rsquo;entra\u00eenement les plus intenses.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c0 qui est destin\u00e9e la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<p>Cette lampe frontale est le compagnon id\u00e9al pour tous les sportifs nocturnes ou matinaux. Que vous soyez un boxeur comme moi, un coureur, un grimpeur ou m\u00eame un <a href=\"https:\/\/boxeur-pro.fr\/it\/allenamento-fisico-negli-sport-da-combattimento\/\" data-lasso-id=\"5741\">adepte de la pr\u00e9paration physique en sport de combat<\/a>, la Swift RL s&rsquo;adaptera \u00e0 vos besoins. Elle est particuli\u00e8rement pratique pour les entra\u00eenements en ext\u00e9rieur quand la luminosit\u00e9 est faible.<\/p>\n\n\n\n<p>J&rsquo;ai m\u00eame vu des randonneurs l&rsquo;utiliser pour leurs exp\u00e9ditions nocturnes. C&rsquo;est dire si elle est polyvalente ! Et pour les amateurs de trail running, c&rsquo;est comme avoir un phare de voiture sur la t\u00eate, mais en beaucoup plus l\u00e9ger.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les sp\u00e9cificit\u00e9s techniques de la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<affilizz-rendering-component loading=\"lazy\" publication-content-id=\"676068af30999b4329a6265f\"><\/affilizz-rendering-component>\n\n\n\n<p>Parlons un peu technique, histoire de vous impressionner avec quelques chiffres. Cette petite bombe lumineuse ne p\u00e8se que 100 grammes. C&rsquo;est moins lourd que mes <keyword data-keyword-id=\"878\"><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/meilleur-gant-de-boxe-comparatif\/\">guanti da boxe<\/a><\/keyword>, je vous le garantis ! Elle offre une puissance maximale de 900 lumens, de quoi faire p\u00e2lir les lampadaires du quartier.<\/p>\n\n\n\n<p>Le temps de charge est d&rsquo;environ 6 heures, et la batterie lithium-ion de 2350 mAh vous assure une autonomie variable selon le mode utilis\u00e9. Et pour les geeks de la s\u00e9curit\u00e9, sachez qu&rsquo;elle est certifi\u00e9e IP X4, ce qui signifie qu&rsquo;elle r\u00e9siste aux intemp\u00e9ries. Parfait pour les entra\u00eenements sous la pluie !<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment la Petzl Swift RL &#8211; 900 lumens se situe-t-elle sur le march\u00e9<\/h2>\n\n\n\n<p>Sur le ring des lampes frontales, la Swift RL &#8211; 900 lumens se positionne clairement comme un <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-poids\/\">peso<\/a> lourd. Compar\u00e9e \u00e0 d&rsquo;autres mod\u00e8les, elle se d\u00e9marque par sa technologie Reactive Lighting, un v\u00e9ritable atout pour optimiser l&rsquo;autonomie et le confort d&rsquo;utilisation.<\/p>\n\n\n\n<p>Par rapport \u00e0 sa petite s\u0153ur, la Petzl Actik Core 600 lumens, elle offre une puissance sup\u00e9rieure et une meilleure port\u00e9e. Pourtant, certains concurrents comme la Ledlenser H8R proposent une autonomie l\u00e9g\u00e8rement sup\u00e9rieure, mais avec une puissance moindre. C&rsquo;est un peu comme choisir entre un boxeur puissant mais qui fatigue vite, et un boxeur endurant mais moins percutant.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avantages de la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<p>Les points forts de cette lampe sont nombreux. Sa l\u00e9g\u00e8ret\u00e9 est un vrai plus, on l&rsquo;oublie presque une fois sur la t\u00eate. La technologie Reactive Lighting est un game-changer, permettant d&rsquo;optimiser l&rsquo;autonomie tout en gardant les mains libres. J&rsquo;appr\u00e9cie particuli\u00e8rement le bouton unique pour g\u00e9rer toutes les fonctions, c&rsquo;est pratique quand on a les mains dans les gants ou en plein effort.<\/p>\n\n\n\n<p>Le bandeau ergonomique et r\u00e9fl\u00e9chissant est un autre atout. Il assure un maintien parfait, m\u00eame pendant les mouvements brusques, et augmente la visibilit\u00e9. C&rsquo;est comme porter un <a href=\"https:\/\/boxeur-pro.fr\/it\/blog\/i-migliori-leggings-modellanti-per-lo-sport-i-nostri-confronti-piu-efficaci\/\" data-lasso-id=\"5742\">legging sport gainant<\/a> pour la t\u00eate, confortable et efficace !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Inconv\u00e9nients de la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<p>Bien s\u00fbr, aucun produit n&rsquo;est parfait, m\u00eame dans le monde de la boxe. Le prix de la Swift RL peut \u00eatre un frein pour certains. C&rsquo;est un investissement, certes, mais pour la qualit\u00e9 propos\u00e9e, \u00e7a vaut le coup. Le temps de charge de 6 heures peut aussi sembler long, surtout si on oublie de la brancher apr\u00e8s une s\u00e9ance nocturne.<\/p>\n\n\n\n<p>Certains utilisateurs ont not\u00e9 que le mode Reactive Lighting pouvait parfois \u00eatre un peu trop sensible, changeant rapidement d&rsquo;intensit\u00e9 dans des environnements vari\u00e9s. C&rsquo;est un peu comme un arbitre trop z\u00e9l\u00e9 qui interrompt le combat \u00e0 la moindre occasion.<\/p>\n\n\n\n<affilizz-rendering-component loading=\"lazy\" publication-content-id=\"676068af30999b4329a6265f\"><\/affilizz-rendering-component>\n\n\n\n<h3 class=\"wp-block-heading\">Conseils d&rsquo;utilisation de la Petzl Swift RL &#8211; 900 lumens<\/h3>\n\n\n\n<p>Pour tirer le meilleur de cette lampe, je vous conseille de toujours la recharger apr\u00e8s utilisation. Utilisez le mode Reactive Lighting pour optimiser l&rsquo;autonomie, mais n&rsquo;h\u00e9sitez pas \u00e0 passer en mode Standard si vous avez besoin d&rsquo;une luminosit\u00e9 constante. Pensez \u00e0 nettoyer r\u00e9guli\u00e8rement le bandeau, il est lavable et \u00e7a \u00e9vitera les mauvaises odeurs apr\u00e8s vos s\u00e9ances intenses.<\/p>\n\n\n\n<p>N&rsquo;oubliez pas d&rsquo;utiliser la fonction LOCK lors du transport pour \u00e9viter tout allumage intempestif. Et si vous partez pour une longue exp\u00e9dition, emportez un chargeur portable, histoire de pouvoir recharger votre lampe en cas de besoin.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Conclusione<\/h4>\n\n\n\n<p>Tout compte fait, la Petzl Swift RL &#8211; 900 lumens est comme un bon partenaire d&rsquo;entra\u00eenement : fiable, performante et toujours pr\u00eate \u00e0 vous accompagner dans vos d\u00e9fis. Avec sa puissance impressionnante, son confort d&rsquo;utilisation et sa technologie intelligente, elle m\u00e9rite vraiment sa place sur le podium des lampes frontales. Alors, que vous soyez un boxeur noctambule comme moi ou simplement un amateur de sport en qu\u00eate de lumi\u00e8re, cette petite merveille pourrait bien devenir votre meilleure alli\u00e9e. Allez, on \u00e9teint les lumi\u00e8res et on sort s&rsquo;entra\u00eener !<\/p>\n\n\n\n<p>Fonti :<br>&#8211; https:\/\/www.petzl.com\/<br>&#8211; https:\/\/www.lampe-frontale.info\/<br>&#8211; https:\/\/www.ffrandonnee.fr\/<\/p>\n\n\n\n<div style=\"text-align: center;\"><iframe class=\"\" src=\"https:\/\/www.youtube.com\/embed\/pPBVW_8VLdI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"<p>Ciao amici! Oggi parliamo di un'attrezzatura che illuminer\u00e0 le vostre sessioni di allenamento notturne. S\u00ec, anche noi pugili a volte abbiamo bisogno di un po' di luce per vedere dove stiamo andando. Indossate quindi i guanti e date un'occhiata al Petzl Swift RL... <a title=\"Petzl Swift RL &#8211; 900 lumens : avis sur la lampe frontale\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/\" aria-label=\"Per saperne di pi\u00f9 su Petzl Swift RL &#8211; 900 lumens : avis sur la lampe frontale\">Leggi tutto<\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3215","post","type-post","status-publish","format-standard","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Petzl Swift RL - 900 lumens : avis sur la lampe frontale - Boxeur PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petzl Swift RL - 900 lumens : avis sur la lampe frontale - Boxeur PRO\" \/>\n<meta property=\"og:description\" content=\"Salut les amis ! Aujourd&rsquo;hui, on va parler d&rsquo;un \u00e9quipement qui va illuminer vos sessions d&rsquo;entra\u00eenement nocturnes. Eh oui, m\u00eame nous les boxeurs, on a parfois besoin d&rsquo;un peu de lumi\u00e8re pour voir o\u00f9 on met les pieds. Alors, attachez vos gants, on va \u00e9tudier ensemble la Petzl Swift RL ... Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-16T16:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-16T18:06:49+00:00\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Petzl Swift RL &#8211; 900 lumens : avis sur la lampe frontale\",\"datePublished\":\"2024-12-16T16:56:00+00:00\",\"dateModified\":\"2024-12-16T18:06:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/\"},\"wordCount\":1104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/\",\"name\":\"Petzl Swift RL - 900 lumens : avis sur la lampe frontale - Boxeur PRO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\"},\"datePublished\":\"2024-12-16T16:56:00+00:00\",\"dateModified\":\"2024-12-16T18:06:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/petzl-swift-rl-900-lumens-avis-lampe-frontale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petzl Swift RL &#8211; 900 lumens : avis sur la lampe frontale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petzl Swift RL - 900 lumens : avis sur la lampe frontale - Boxeur PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/","og_locale":"it_IT","og_type":"article","og_title":"Petzl Swift RL - 900 lumens : avis sur la lampe frontale - Boxeur PRO","og_description":"Salut les amis ! Aujourd&rsquo;hui, on va parler d&rsquo;un \u00e9quipement qui va illuminer vos sessions d&rsquo;entra\u00eenement nocturnes. Eh oui, m\u00eame nous les boxeurs, on a parfois besoin d&rsquo;un peu de lumi\u00e8re pour voir o\u00f9 on met les pieds. Alors, attachez vos gants, on va \u00e9tudier ensemble la Petzl Swift RL ... Leggi tutto","og_url":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/","og_site_name":"Boxeur PRO","article_published_time":"2024-12-16T16:56:00+00:00","article_modified_time":"2024-12-16T18:06:49+00:00","author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maxime","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Petzl Swift RL &#8211; 900 lumens : avis sur la lampe frontale","datePublished":"2024-12-16T16:56:00+00:00","dateModified":"2024-12-16T18:06:49+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/"},"wordCount":1104,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"articleSection":["Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/","url":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/","name":"Petzl Swift RL - 900 lumens : avis sur la lampe frontale - Boxeur PRO","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/#website"},"datePublished":"2024-12-16T16:56:00+00:00","dateModified":"2024-12-16T18:06:49+00:00","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/it\/blog\/petzl-swift-rl-900-lumens-avis-lampe-frontale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Petzl Swift RL &#8211; 900 lumens : avis sur la lampe frontale"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/it\/#website","url":"https:\/\/boxeur-pro.fr\/it\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/it\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/it\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/3215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/comments?post=3215"}],"version-history":[{"count":1,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/3215\/revisions"}],"predecessor-version":[{"id":3219,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/3215\/revisions\/3219"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/media?parent=3215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/categories?post=3215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/tags?post=3215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}