{"id":3275,"date":"2025-01-14T15:42:11","date_gmt":"2025-01-14T14:42:11","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=3275"},"modified":"2025-01-14T15:42:11","modified_gmt":"2025-01-14T14:42:11","slug":"ciryl-gane-altezza-peso-tutto-sul-campione-di-physique","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/","title":{"rendered":"Ciryl gane peso forma: tutto quello che c'\u00e8 da sapere sul fisico del campione"},"content":{"rendered":"<p><strong>L'articolo in breve<\/strong><\/p>\n<p>Ciryl Gane, soprannominato \"Bon Gamin\", \u00e8 un lottatore francese di MMA dal fisico imponente e dalle prestazioni eccezionali. Ecco i punti chiave:<\/p>\n<ul>\n<li><strong>Dimensioni impressionanti<\/strong> 1,93 m, 112 kg<\/li>\n<li>Estensione <i>notevole<\/i> di 206 cm<\/li>\n<li>Corso <strong>abbagliante<\/strong> nell'UFC con 10 vittorie in 12 incontri.<\/li>\n<li>Stile di combattimento <i>unico<\/i> combinando muay-thai e jiu-jitsu brasiliano<\/li>\n<li>Un futuro promettente con un incontro previsto contro Alexander Volkov nel 2024<\/li>\n<\/ul>\n<p>Ciryl Gane, soprannominato \"Bon Gamin\", \u00e8 una figura di spicco delle MMA francesi. Questo lottatore impareggiabile \u00e8 noto per le sue prestazioni eccezionali e per il suo fisico imponente. Addentriamoci nel mondo di questo campione per scoprire i dettagli della sua carriera. <strong><a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-taille\/\">dimensione<\/a> e il suo <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/mike-tyson-poids\/\">peso<\/a><\/strong>Tutte caratteristiche che lo rendono un atleta formidabile.<\/p>\n<h2>L'imponente statura di Ciryl Gane<\/h2>\n<p>Ciryl Gane \u00e8 una forza fisica con cui fare i conti nell'ottagono. La sua imponente statura gli conferisce un chiaro vantaggio sugli avversari. Diamo un'occhiata pi\u00f9 da vicino alle misure di questo colosso delle MMA:<\/p>\n<h3>Altezza e peso di Ciryl Gane<\/h3>\n<p>Il caccia francese ha un <strong>altezza 1,93 m<\/strong>6 piedi e 4 pollici. Questa altezza gli permette di dominare la maggior parte dei suoi avversari. Per quanto riguarda il suo <strong>peso<\/strong>\u00e8 intorno a <strong>112 kg<\/strong> (247 libbre), collocandosi comodamente nella categoria dei pesi massimi dell'UFC, il cui limite \u00e8 fissato a 120,2 kg (265 libbre).<\/p>\n<h3>Altre misure degne di nota<\/h3>\n<p>Oltre all'altezza e al peso, Ciryl Gane ha altre caratteristiche fisiche degne di nota:<\/p>\n<ul>\n<li>Un'estensione di 206 cm (81 pollici)<\/li>\n<li>Estensione delle gambe di 107 cm (42 pollici)<\/li>\n<\/ul>\n<p>Queste caratteristiche gli permettono di tenere gli avversari a distanza e di sfruttare appieno le sue doti di <a href=\"https:\/\/boxeur-pro.fr\/it\/boxe\/meilleur-sac-de-frappe-boxe\/\">colpito<\/a>.<\/p>\n<h3>Un fisico atipico per un peso massimo<\/h3>\n<p>Nonostante la sua corporatura imponente, Gane \u00e8 noto per la sua eccezionale mobilit\u00e0 e velocit\u00e0 per un combattente della sua categoria. Questa agilit\u00e0, unita alla sua potenza, lo rende un avversario formidabile sul ring.<\/p>\n<h2>Carriera e performance di Ciryl Gane<\/h2>\n<p>La carriera di Ciryl Gane nel mondo degli sport da combattimento \u00e8 impressionante quanto il suo fisico. Nato il 12 aprile 1990 a La Roche-sur-Yon, in Vandea, questo atleta di origini vandeane e della Guadalupa \u00e8 arrivato ai vertici della scena mondiale delle MMA.<\/p>\n<h3>Un inizio promettente<\/h3>\n<p>Prima di dedicarsi alle MMA, Gane si \u00e8 distinto nella muay-thai, diventando campione francese nel 2016 e nel 2017. Solo all'et\u00e0 di 28 anni, nel 2018, ha fatto il suo debutto nelle MMA professionistiche. Questo passaggio tardivo non ha impedito al \"Good Kid\" di scalare rapidamente le classifiche.<\/p>\n<h3>Una carriera folgorante nell'UFC<\/h3>\n<p>Dal suo arrivo nell'UFC, Ciryl Gane ha accumulato una lista impressionante di successi:<\/p>\n<table>\n<tr>\n<th>Statistiche<\/th>\n<th>Dettagli<\/th>\n<\/tr>\n<tr>\n<td>Numero di combattimenti<\/td>\n<td>12<\/td>\n<\/tr>\n<tr>\n<td>Vittorie<\/td>\n<td>10<\/td>\n<\/tr>\n<tr>\n<td>Sconfitte<\/td>\n<td>2<\/td>\n<\/tr>\n<\/table>\n<p>Tra i suoi successi c'\u00e8 il titolo di campione ad interim dei pesi massimi UFC. Nel marzo 2023 ha combattuto <a href=\"https:\/\/boxeur-pro.fr\/it\/stipe-miocic\/\" data-lasso-id=\"5895\">Stipe Miocic<\/a> per il titolo vacante dei pesi massimi, un incontro che si \u00e8 concluso con una sconfitta ma che ha dimostrato la sua capacit\u00e0 di affrontare i migliori.<\/p>\n<h3>Stile di combattimento e allenamento<\/h3>\n<p>Lo stile di combattimento di Ciryl Gane \u00e8 una miscela unica di muay-thai e jiu-jitsu brasiliano. Questa combinazione, unita alla sua sorprendente mobilit\u00e0 per un atleta della sua statura, lo rende un combattente versatile e imprevedibile. Si allena alla MMA Factory di Parigi sotto la guida di Fernand Lopez, un noto allenatore del settore.<\/p>\n<p><img decoding=\"async\" src=\"\" alt=\"Ciryl gane peso forma: tutto quello che c&#039;\u00e8 da sapere sul fisico del campione\" class=\"\"><\/p>\n<h2>Un futuro luminoso per Ciryl Gane<\/h2>\n<p>All'et\u00e0 di 34 anni, nel 2024, Ciryl Gane ha ancora grandi anni davanti a s\u00e9 nel mondo delle MMA. La sua prossima sfida \u00e8 gi\u00e0 programmata: un incontro contro Alexander Volkov a UFC 310 nel dicembre 2024. Questo incontro sar\u00e0 l'occasione per il francese di dimostrare ancora una volta le sue capacit\u00e0 e di avvicinarsi a un'altra occasione di titolo.<\/p>\n<p>L'evoluzione di <a href=\"https:\/\/boxeur-pro.fr\/it\/pugilato\/francis-ngannou-fortuna\/\" data-lasso-id=\"5896\">La fortuna di Francis Ngannou<\/a>un altro peso massimo iconico, mostra il potenziale finanziario che un pugile di alto livello come Gane pu\u00f2 raggiungere. Anche se le cifre esatte dei suoi guadagni non sono state rese note, \u00e8 certo che le sue prestazioni e la sua crescente popolarit\u00e0 gli assicurano un futuro finanziario confortevole.<\/p>\n<p>In definitiva, Ciryl Gane incarna il perfetto equilibrio tra potenza e agilit\u00e0 nella categoria dei pesi massimi. Il suo <i>dimensione<\/i> e il suo <i>peso<\/i>Grazie alla sua tecnica raffinata e alla mentalit\u00e0 da campione, \u00e8 uno dei pugili pi\u00f9 promettenti della sua generazione. Sia all'interno che all'esterno dell'ottagono, il \"Good Kid\" continua a stupire e a superare i limiti che un atleta della sua categoria pu\u00f2 raggiungere.<\/p>\n<p>Fonti :<br \/>\n<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"5897\">wiki pugilato<\/a><br \/>\n<a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"5898\">sito dei combattenti<\/a><\/p>\n<div style=\"text-align:center;\"><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/WzPFGHMuGIk\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen class=\"\"><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"<p>L'articolo in breve Ciryl Gane, soprannominato \"Bon Gamin\", \u00e8 un lottatore francese di MMA dal fisico imponente e dalle prestazioni eccezionali. Ecco i punti salienti: stazza imponente: 1,93 m per 112 kg, altezza notevole di 206 cm, carriera folgorante nell'UFC con 10 vittorie in 12 incontri, stile di lotta ... <a title=\"Ciryl gane peso forma: tutto quello che c&#039;\u00e8 da sapere sul fisico del campione\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/\" aria-label=\"Per saperne di pi\u00f9 su Ciryl gane taille poids : tout savoir sur le physique du champion\">Leggi tutto<\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3275","post","type-post","status-publish","format-standard","hentry","category-boxe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciryl gane taille poids : tout savoir sur le physique du champion - Boxeur PRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-altezza-peso-tutto-sul-campione-di-physique\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciryl gane taille poids : tout savoir sur le physique du champion - Boxeur PRO\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;article en bref Ciryl Gane, surnomm\u00e9 \u00ab\u00a0Bon Gamin\u00a0\u00bb, est un combattant fran\u00e7ais de MMA au physique impressionnant et aux performances exceptionnelles. Voici les points cl\u00e9s : Gabarit imposant : 1,93 m pour 112 kg Allonge remarquable de 206 cm Parcours fulgurant \u00e0 l&rsquo;UFC avec 10 victoires en 12 combats Style ... Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-altezza-peso-tutto-sul-campione-di-physique\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-14T14:42:11+00:00\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Ciryl gane taille poids : tout savoir sur le physique du champion\",\"datePublished\":\"2025-01-14T14:42:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/\"},\"wordCount\":820,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"articleSection\":[\"Boxe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/\",\"name\":\"Ciryl gane taille poids : tout savoir sur le physique du champion - Boxeur PRO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\"},\"datePublished\":\"2025-01-14T14:42:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/blog\\\/ciryl-gane-taille-poids-tout-savoir-physique-champion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciryl gane taille poids : tout savoir sur le physique du champion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/it\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciryl gane: tutto quello che c'\u00e8 da sapere sul fisico del campione - Boxeur PRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-altezza-peso-tutto-sul-campione-di-physique\/","og_locale":"it_IT","og_type":"article","og_title":"Ciryl gane taille poids : tout savoir sur le physique du champion - Boxeur PRO","og_description":"L&rsquo;article en bref Ciryl Gane, surnomm\u00e9 \u00ab\u00a0Bon Gamin\u00a0\u00bb, est un combattant fran\u00e7ais de MMA au physique impressionnant et aux performances exceptionnelles. Voici les points cl\u00e9s : Gabarit imposant : 1,93 m pour 112 kg Allonge remarquable de 206 cm Parcours fulgurant \u00e0 l&rsquo;UFC avec 10 victoires en 12 combats Style ... Leggi tutto","og_url":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-altezza-peso-tutto-sul-campione-di-physique\/","og_site_name":"Boxeur PRO","article_published_time":"2025-01-14T14:42:11+00:00","author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Maxime","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Ciryl gane taille poids : tout savoir sur le physique du champion","datePublished":"2025-01-14T14:42:11+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/"},"wordCount":820,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"articleSection":["Boxe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/","url":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/","name":"Ciryl gane: tutto quello che c'\u00e8 da sapere sul fisico del campione - Boxeur PRO","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/it\/#website"},"datePublished":"2025-01-14T14:42:11+00:00","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/it\/blog\/ciryl-gane-taille-poids-tout-savoir-physique-champion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Ciryl gane taille poids : tout savoir sur le physique du champion"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/it\/#website","url":"https:\/\/boxeur-pro.fr\/it\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/it\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/it\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/it\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/3275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/comments?post=3275"}],"version-history":[{"count":1,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/3275\/revisions"}],"predecessor-version":[{"id":3286,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/posts\/3275\/revisions\/3286"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/media?parent=3275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/categories?post=3275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/it\/wp-json\/wp\/v2\/tags?post=3275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}