{"id":2544,"date":"2024-09-02T15:51:50","date_gmt":"2024-09-02T13:51:50","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2544"},"modified":"2024-09-02T15:51:51","modified_gmt":"2024-09-02T13:51:51","slug":"daniel-cormier-a-sua-historia-altura-peso-idade-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/","title":{"rendered":"Daniel Cormier: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Breve resumo do artigo<\/h4>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Daniel Cormier<\/strong><\/th><th><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-taille\/\">Tamanho<\/a><\/strong><\/th><th><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong><\/th><th><strong>Idade<\/strong><\/th><th><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-fortune\/\">A fortuna<\/a><\/strong><\/th><\/tr><\/thead><tbody><tr><td>1m80<\/td><td>114 kg<\/td><td>45 anos de idade<\/td><td>7 milh\u00f5es $<\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Introdu\u00e7\u00e3o<\/h3>\n\n\n\n<p>Ol\u00e1 a todos os f\u00e3s do desporto e das artes marciais mistas! Hoje vamos mergulhar no mundo fascinante de um homem que deixou a sua marca na hist\u00f3ria das MMA: Daniel Cormier. Provavelmente j\u00e1 ouviram o seu nome, viram os seus combates, ou talvez o tenham ouvido comentar os combates com a sua voz inconfund\u00edvel. Mas, para al\u00e9m do atleta, quem \u00e9 realmente Daniel Cormier? Qual \u00e9 o seu passado e como \u00e9 que um rapaz de Lafayette, Louisiana, se tornou numa lenda viva? Vamos falar da sua carreira, mas tamb\u00e9m daquilo que o torna \u00fanico: a sua hist\u00f3ria pessoal, o seu tamanho impressionante, a sua idade e, claro, a pergunta que todos t\u00eam na cabe\u00e7a: quanto pesa a sua conta banc\u00e1ria depois de todos estes anos de combates?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Daniel Cormier: hist\u00f3ria, altura, peso, idade, fortuna<\/h2>\n\n\n\n<p>Quando se fala no nome de Daniel Cormier, h\u00e1 tanto para dizer que \u00e9 dif\u00edcil saber por onde come\u00e7ar. Nascido a 20 de mar\u00e7o de 1979 em Lafayette, Louisiana, Daniel Ryan Cormier (nome verdadeiro) n\u00e3o teve uma inf\u00e2ncia f\u00e1cil. Cresceu no seio de uma fam\u00edlia modesta e, desde muito cedo, teve de enfrentar desafios que teriam destro\u00e7ado muita gente. O seu pai foi assassinado quando ele tinha apenas sete anos de idade, um acontecimento traum\u00e1tico que teve um efeito profundo na sua vida. Mas foi talvez essa dor que forjou o seu car\u00e1cter e o levou a tornar-se o lutador resiliente que \u00e9 hoje.<\/p>\n\n\n\n<p>Daniel Cormier \u00e9 mais do que um lutador de MMA; \u00e9 um homem que superou os seus dem\u00f3nios para chegar ao topo. Com 1,80m e 114kg, ele \u00e9 o que se chama de peso pesado. Mas o seu tamanho \u00e9 apenas um dos aspectos que o tornam formid\u00e1vel. O que realmente impressiona \u00e9 a sua for\u00e7a bruta combinada com uma t\u00e9cnica excecional, forjada por anos de luta ao mais alto n\u00edvel. Aos 45 anos, est\u00e1 reformado, mas a sua presen\u00e7a no mundo dos desportos de combate \u00e9 mais forte do que nunca, nomeadamente gra\u00e7as ao seu papel de comentador e analista da UFC.<\/p>\n\n\n\n<p>Quando se trata de finan\u00e7as, Daniel Cormier n\u00e3o tem nada a invejar a ningu\u00e9m. Depois de uma carreira t\u00e3o rica e variada, acumulou uma fortuna avaliada em cerca de 7 milh\u00f5es de d\u00f3lares. N\u00e3o \u00e9 de admirar, se pensarmos que os melhores lutadores do mundo podem ganhar somas consider\u00e1veis, n\u00e3o s\u00f3 com os seus combates, mas tamb\u00e9m com patroc\u00ednios, apari\u00e7\u00f5es na televis\u00e3o e, agora para ele, com coment\u00e1rios desportivos. Uma carreira bem conseguida, que lhe permitiu tirar partido do seu talento como lutador, mas tamb\u00e9m do seu carisma e intelig\u00eancia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A estreia de Daniel Cormier no wrestling<\/h3>\n\n\n\n<p>Antes de se tornar uma superestrela do MMA, Daniel Cormier construiu a sua identidade desportiva nos tapetes de luta livre. A luta livre foi onde tudo come\u00e7ou para ele. Desde muito cedo, Cormier refugiou-se no desporto que viria a tornar-se a sua paix\u00e3o e voca\u00e7\u00e3o. No liceu, j\u00e1 dominava os seus advers\u00e1rios e ganhou uma bolsa de estudo para a Universidade do Estado de Oklahoma. A\u00ed, continuou a aperfei\u00e7oar a sua arte, tornando-se rapidamente num dos melhores lutadores do pa\u00eds.<\/p>\n\n\n\n<p>Cormier atingiu o auge da luta livre amadora ao representar os Estados Unidos nos Jogos Ol\u00edmpicos de 2004 e 2008. Mas o seu sonho ol\u00edmpico sofreu um rude golpe em 2008, quando foi for\u00e7ado a retirar-se devido a problemas de sa\u00fade relacionados com a m\u00e1 gest\u00e3o do peso. Apesar deste rev\u00e9s, a sua carreira de lutador continua a ser impressionante, com t\u00edtulos nacionais e medalhas nos Campeonatos do Mundo. Estas experi\u00eancias n\u00e3o s\u00f3 o forjaram como atleta, mas tamb\u00e9m lhe deram as bases necess\u00e1rias para ter sucesso nas MMA.<\/p>\n\n\n\n<p>A transi\u00e7\u00e3o do wrestling para as MMA n\u00e3o foi f\u00e1cil para Cormier. Teve de se adaptar a um novo estilo de luta, aprender novas t\u00e9cnicas e enfrentar advers\u00e1rios com estilos muito diferentes. Mas gra\u00e7as \u00e0 sua s\u00f3lida base de wrestling e \u00e0 sua inabal\u00e1vel \u00e9tica de trabalho, rapidamente se estabeleceu como um advers\u00e1rio formid\u00e1vel. A sua capacidade de controlar os advers\u00e1rios no ch\u00e3o, combinada com uma <a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/meilleur-sac-de-frappe-boxe\/\">atingido<\/a> transformou-o num lutador completo, capaz de competir com os melhores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A ascens\u00e3o das MMA<\/h3>\n\n\n\n<p>Depois de uma carreira brilhante no wrestling, Daniel Cormier entrou no mundo das MMA em 2009. Para muitos, foi uma surpresa, mas para aqueles que conheciam o seu passado, foi uma progress\u00e3o natural. Come\u00e7ou a sua carreira profissional na organiza\u00e7\u00e3o Strikeforce, onde rapidamente mostrou que n\u00e3o estava ali apenas para fazer n\u00famero. Desde os seus primeiros combates, impressionou com a sua capacidade de marcar o ritmo e ditar o resultado dos combates com o seu wrestling e poder de elite.<\/p>\n\n\n\n<p>O ponto de viragem na sua carreira ocorreu, sem d\u00favida, no torneio Strikeforce Heavyweight Grand Prix, em 2011. Entrando como substituto de \u00faltima hora, Cormier n\u00e3o s\u00f3 venceu, como dominou os seus advers\u00e1rios, provando que podia competir com os melhores lutadores do mundo. Este torneio lan\u00e7ou realmente a sua carreira e colocou-o no radar da UFC, a maior organiza\u00e7\u00e3o de MMA do mundo.<\/p>\n\n\n\n<p>Quando entrou para a UFC, Cormier continuou a construir o seu sucesso. Tornou-se um dos poucos lutadores a conquistar t\u00edtulos em duas categorias de peso diferentes: peso-leve e peso-pesado. Esta dupla coroa \u00e9 um feito raro e um testemunho da sua versatilidade e talento bruto. As suas vit\u00f3rias sobre lutadores de topo como Josh Barnett, Dan Henderson e Anthony Johnson cimentaram o seu estatuto de lenda do desporto. Cada combate parecia ser um novo desafio, mas Cormier estava sempre \u00e0 altura da ocasi\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Batalhas lend\u00e1rias<\/h3>\n\n\n\n<p>Quando se fala de Daniel Cormier, \u00e9 imposs\u00edvel n\u00e3o recordar os seus confrontos lend\u00e1rios. Entre os mais memor\u00e1veis est\u00e3o, naturalmente, os seus duelos com Jon Jones. Essas lutas chamaram a aten\u00e7\u00e3o de f\u00e3s do mundo todo, n\u00e3o s\u00f3 pela qualidade do espet\u00e1culo, mas tamb\u00e9m pela intensa rivalidade entre os dois homens. A primeira luta, em 2015, vencida por Jones, mostrou que Cormier ainda tinha espa\u00e7o para melhorar. Mas o segundo combate, em 2017, apesar de pol\u00e9mico devido ao teste de doping positivo de Jones, mostrou a tenacidade de Cormier, que nunca desistiu.<\/p>\n\n\n\n<p>Mas Cormier n\u00e3o se limitou a Jon Jones. Ele tamb\u00e9m enfrentou Stipe Miocic, considerado por muitos como o maior peso pesado da hist\u00f3ria do UFC. A trilogia deles foi uma das mais intensas da hist\u00f3ria do MMA. Cormier surpreendeu a todos ao vencer Miocic em sua primeira luta em 2018 para se tornar campe\u00e3o dos pesos pesados. Essa luta mostrou o qu\u00e3o perigoso ele era, mesmo contra advers\u00e1rios maiores e mais pesados. Por\u00e9m, nas duas lutas seguintes, Miocic conseguiu levar a melhor novamente, mas isso s\u00f3 refor\u00e7ou o respeito que f\u00e3s e lutadores t\u00eam por Cormier.<\/p>\n\n\n\n<p>Estes duelos marcaram uma era no MMA. Eles mostraram que Daniel Cormier n\u00e3o era apenas um atleta excecional, mas tamb\u00e9m um lutador com determina\u00e7\u00e3o inabal\u00e1vel. Independentemente do advers\u00e1rio ou das circunst\u00e2ncias, Cormier sempre mostrou que tinha o cora\u00e7\u00e3o de um campe\u00e3o. E mesmo na derrota, ele sabia como manter seu esp\u00edrito vivo. <a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/meilleur-casque-de-boxe\/\">cabe\u00e7a<\/a> demonstrando que a verdadeira grandeza n\u00e3o reside apenas na vit\u00f3ria, mas tamb\u00e9m na capacidade de enfrentar as adversidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A reforma e a vida depois do combate<\/h3>\n\n\n\n<p>Depois de dar tudo de si no oct\u00f3gono, Daniel Cormier tomou uma decis\u00e3o dif\u00edcil mas inevit\u00e1vel em 2020: retirar-se do MMA como lutador ativo. Aos 41 anos, ele j\u00e1 havia conquistado tudo. O seu corpo, posto \u00e0 prova ao longo de d\u00e9cadas de combates e sparring, come\u00e7ava a dar sinais de cansa\u00e7o. Mas Cormier n\u00e3o era de ficar sentado sem fazer nada. Em vez de desaparecer do radar, optou por permanecer no mundo do desporto de que tanto gosta, mas de uma forma diferente.<\/p>\n\n\n\n<p>Atualmente, Daniel Cormier \u00e9 uma das vozes mais respeitadas da UFC. Como comentarista e analista, ele traz uma perspetiva \u00fanica para os combates.<\/p>\n\n\n\n<p>Gra\u00e7as \u00e0 sua experi\u00eancia como lutador e lutador. A sua abordagem \u00e9 simultaneamente t\u00e9cnica e acess\u00edvel, o que o torna muito popular entre os f\u00e3s, quer sejam principiantes ou especialistas em MMA. Mas isso n\u00e3o \u00e9 tudo. Cormier \u00e9 tamb\u00e9m um treinador apaixonado. Partilha os seus conhecimentos com a pr\u00f3xima gera\u00e7\u00e3o de lutadores, ajudando-os a prepararem-se n\u00e3o s\u00f3 para a competi\u00e7\u00e3o, mas tamb\u00e9m para a vida fora do ringue.<\/p>\n\n\n\n<p>A transi\u00e7\u00e3o de lutador para comentador e treinador \u00e9 muitas vezes dif\u00edcil para os atletas de alto n\u00edvel, mas Cormier fez uma transi\u00e7\u00e3o brilhante. Aproveitou a sua carreira de forma inteligente, diversificando as suas actividades e mantendo-se ativo numa \u00e1rea que o apaixona. Para ele, a reforma n\u00e3o significa descanso, mas sim uma nova etapa na sua vida, onde continua a contribuir para a comunidade MMA enquanto constr\u00f3i o seu legado fora da jaula.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Daniel Cormier e a sua fortuna<\/h3>\n\n\n\n<p>Quanto \u00e9 que vale Daniel Cormier? Depois de uma carreira t\u00e3o not\u00e1vel, n\u00e3o \u00e9 de admirar que a sua fortuna esteja estimada em cerca de 7 milh\u00f5es de d\u00f3lares. Mas de onde vem esse dinheiro? Obviamente, muito dele vem das suas lutas. Os maiores lutadores do UFC podem ganhar milh\u00f5es, especialmente quando atingem o topo como Cormier fez. Mas o seu rendimento n\u00e3o se limita ao dinheiro ganho no oct\u00f3gono.<\/p>\n\n\n\n<p>Os acordos de patroc\u00ednio tamb\u00e9m desempenharam um papel crucial. As marcas de prest\u00edgio procuram sempre associar-se a atletas como Cormier, que representam tanto o sucesso desportivo como a for\u00e7a de car\u00e1cter. Para al\u00e9m disso, os seus pap\u00e9is como comentador da UFC e como analista na ESPN permitiram-lhe continuar a ganhar um sal\u00e1rio confort\u00e1vel, mantendo-se na ribalta.<\/p>\n\n\n\n<p>O que torna Cormier diferente de muitos outros atletas \u00e9 a sua intelig\u00eancia financeira. Ele investiu seu dinheiro com sabedoria, garantindo seguran\u00e7a financeira a longo prazo. N\u00e3o \u00e9 raro os atletas gerirem mal as suas finan\u00e7as, mas Cormier evitou essa armadilha ao tomar decis\u00f5es informadas ao longo da sua carreira. Ganhou a sua fortuna com o suor do seu rosto e isso \u00e9 um reflexo n\u00e3o s\u00f3 do seu sucesso no ringue, mas tamb\u00e9m da sua sabedoria fora dele.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A personalidade de Daniel Cormier<\/h3>\n\n\n\n<p>Mais do que um lutador, Daniel Cormier \u00e9 um homem com uma personalidade que conquistou um vasto p\u00fablico. O que se destaca imediatamente nele \u00e9 a sua autenticidade. Cormier nunca tentou desempenhar um papel ou conformar-se com os estere\u00f3tipos frequentemente associados aos lutadores. Manteve-se fiel a si pr\u00f3prio, quer na vit\u00f3ria quer na derrota. Esta autenticidade valeu-lhe o respeito n\u00e3o s\u00f3 dos seus f\u00e3s, mas tamb\u00e9m dos seus pares.<\/p>\n\n\n\n<p>Daniel Cormier \u00e9 tamb\u00e9m conhecido pelo seu sentido de humor e pela sua capacidade de se rir de si pr\u00f3prio. Esta leveza \u00e9 uma carater\u00edstica rara no mundo dos desportos de combate, onde a press\u00e3o e as expectativas s\u00e3o muitas vezes esmagadoras. Mas Cormier sempre manteve uma atitude positiva, mesmo nos momentos mais dif\u00edceis. Tem esta capacidade de se reconectar com as suas ra\u00edzes, de se manter humilde apesar dos seus sucessos, o que o torna extremamente acess\u00edvel e simp\u00e1tico aos olhos de muitos.<\/p>\n\n\n\n<p>Por fim, o que realmente distingue Cormier \u00e9 o respeito que tem pelos seus advers\u00e1rios e pelo desporto em geral. Num dom\u00ednio em que o \"trash-talking\" \u00e9 um lugar-comum, Cormier sempre preferiu deixar que os seus desempenhos falassem por ele. Manifestou frequentemente a sua admira\u00e7\u00e3o pelos seus advers\u00e1rios, mesmo aqueles com quem tinha rivalidades amargas. Esta atitude de respeito e honra fez dele um modelo a seguir, n\u00e3o s\u00f3 para os jovens lutadores, mas para todos aqueles que aspiram a ter sucesso mantendo os seus valores intactos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conclus\u00e3o<\/h3>\n\n\n\n<p>Daniel Cormier \u00e9 muito mais do que um simples lutador. Ele personifica a resili\u00eancia, a paix\u00e3o e a integridade. Desde os seus primeiros dias no wrestling at\u00e9 \u00e0 sua ascens\u00e3o no MMA, desde os seus lend\u00e1rios duelos at\u00e9 \u00e0 sua transi\u00e7\u00e3o para uma carreira como comentador, cada passo da sua vida \u00e9 um testemunho do seu empenho e determina\u00e7\u00e3o. Hoje, embora j\u00e1 n\u00e3o lute, continua a influenciar o mundo do desporto atrav\u00e9s do seu trabalho como treinador, comentador e mentor. Daniel Cormier \u00e9 a prova viva de que o sucesso n\u00e3o se mede apenas pelas vit\u00f3rias, mas tamb\u00e9m pela forma como se ultrapassam os desafios e se inspiram os outros a fazer o mesmo. Um verdadeiro campe\u00e3o, em todas as frentes. A lenda, j\u00e1 bem estabelecida, ainda est\u00e1 a ser escrita, e o melhor talvez ainda esteja para vir.<\/p>\n\n\n\n<p>Fontes : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4832\">Wiki do boxe <\/a><\/strong><\/p>\n\n\n\n<p>Ver tamb\u00e9m :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4833\"> S\u00edtio Web oficial dos veteranos<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Breve resumo do artigo Daniel Cormier Altura Peso Idade Fortuna 1m80 114 kg 45 anos 7 milh\u00f5es $ Introdu\u00e7\u00e3o Ol\u00e1 a todos os f\u00e3s do desporto e das artes marciais mistas! Hoje, vamos mergulhar no mundo fascinante de um homem que deixou a sua marca na hist\u00f3ria das MMA: Daniel Cormier. Tu ... <a title=\"Daniel Cormier: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/\" aria-label=\"Leia mais sobre Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune\">Ler mais<\/a><\/p>","protected":false},"author":2,"featured_media":2546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Quand on \u00e9voque le nom de Daniel Cormier, il y a tant de choses \u00e0 dire que c\u2019est difficile de savoir par o\u00f9 commencer. N\u00e9 le 20 mars 1979\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Quand on \u00e9voque le nom de Daniel Cormier, il y a tant de choses \u00e0 dire que c\u2019est difficile de savoir par o\u00f9 commencer. N\u00e9 le 20 mars 1979\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-02T13:51:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T13:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/Daniel-Cormier-11-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-09-02T13:51:50+00:00\",\"dateModified\":\"2024-09-02T13:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/\"},\"wordCount\":2416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Daniel-Cormier-11-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/\",\"name\":\"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Daniel-Cormier-11-removebg-preview.png\",\"datePublished\":\"2024-09-02T13:51:50+00:00\",\"dateModified\":\"2024-09-02T13:51:51+00:00\",\"description\":\"Quand on \u00e9voque le nom de Daniel Cormier, il y a tant de choses \u00e0 dire que c\u2019est difficile de savoir par o\u00f9 commencer. N\u00e9 le 20 mars 1979\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Daniel-Cormier-11-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Daniel-Cormier-11-removebg-preview.png\",\"width\":600,\"height\":400,\"caption\":\"Daniel Cormier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/daniel-cormier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daniel Cormier: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio","description":"Quando se fala no nome de Daniel Cormier, h\u00e1 tanto para dizer que \u00e9 dif\u00edcil saber por onde come\u00e7ar. Nasceu a 20 de mar\u00e7o de 1979","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/","og_locale":"pt_PT","og_type":"article","og_title":"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Quand on \u00e9voque le nom de Daniel Cormier, il y a tant de choses \u00e0 dire que c\u2019est difficile de savoir par o\u00f9 commencer. N\u00e9 le 20 mars 1979","og_url":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/","og_site_name":"Boxeur PRO","article_published_time":"2024-09-02T13:51:50+00:00","article_modified_time":"2024-09-02T13:51:51+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/Daniel-Cormier-11-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maxime","Tempo estimado de leitura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-09-02T13:51:50+00:00","dateModified":"2024-09-02T13:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/"},"wordCount":2416,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/Daniel-Cormier-11-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/","url":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/","name":"Daniel Cormier: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/Daniel-Cormier-11-removebg-preview.png","datePublished":"2024-09-02T13:51:50+00:00","dateModified":"2024-09-02T13:51:51+00:00","description":"Quando se fala no nome de Daniel Cormier, h\u00e1 tanto para dizer que \u00e9 dif\u00edcil saber por onde come\u00e7ar. Nasceu a 20 de mar\u00e7o de 1979","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/Daniel-Cormier-11-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/Daniel-Cormier-11-removebg-preview.png","width":600,"height":400,"caption":"Daniel Cormier"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/pt\/daniel-cormier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Daniel Cormier : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/pt\/#website","url":"https:\/\/boxeur-pro.fr\/pt\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/pt\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/pt\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/comments?post=2544"}],"version-history":[{"count":2,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2544\/revisions"}],"predecessor-version":[{"id":2547,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2544\/revisions\/2547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/media\/2546"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/media?parent=2544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/categories?post=2544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/tags?post=2544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}