{"id":2623,"date":"2024-09-12T18:16:39","date_gmt":"2024-09-12T16:16:39","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2623"},"modified":"2024-09-12T18:16:41","modified_gmt":"2024-09-12T16:16:41","slug":"ryan-garcia-a-sua-historia-altura-peso-idade-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/","title":{"rendered":"Ryan Garcia: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Breve resumo do artigo<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Categoria<\/strong><\/th><th><strong>Principais pormenores<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Nome completo<\/strong><\/td><td><strong>Ryan Garcia<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-taille\/\">Tamanho<\/a><\/strong><\/td><td><strong>1m78<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong><\/td><td><strong>Peso leve (61 kg)<\/strong><\/td><\/tr><tr><td><strong>Idade<\/strong><\/td><td><strong>25 anos de idade<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-fortune\/\">A fortuna<\/a><\/strong><\/td><td><strong>10 milh\u00f5es $<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<h3 class=\"wp-block-heading\">Introdu\u00e7\u00e3o<\/h3>\n\n\n\n<p>Ryan Garcia \u00e9 um fen\u00f3meno do boxe neste momento. N\u00e3o \u00e9 poss\u00edvel percorrer o Instagram sem encontrar um dos seus v\u00eddeos de treino ou uma das suas vit\u00f3rias espectaculares. Ele tem aquela coisa que nos deixa viciados. N\u00e3o \u00e9 apenas o seu rosto angelical ou os seus abdominais bem torneados, \u00e9 sobretudo aquela velocidade incr\u00edvel, aquele soco explosivo e aquela mente de a\u00e7o. Em apenas alguns anos, passou de promissor prod\u00edgio a verdadeira estrela, ao ponto de mesmo aqueles que n\u00e3o acompanham o boxe j\u00e1 terem ouvido falar dele.<\/p>\n\n\n\n<p>Mas Ryan Garcia \u00e9 mais do que um simples pugilista. Utilizou as redes sociais como uma arma para aumentar a sua fama e assumir o protagonismo, ao ponto de se ter tornado um \u00edcone para os jovens. Aqui falamos da sua hist\u00f3ria, das suas carater\u00edsticas f\u00edsicas, da sua carreira e de como construiu a sua fortuna com apenas 25 anos de idade. Por isso, cal\u00e7a as luvas e vamos mergulhar no mundo de Ryan Garcia!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ryan Garcia: altura, peso, idade e patrim\u00f3nio<\/h2>\n\n\n\n<p>Ryan Garcia, com 1m78, n\u00e3o \u00e9 o mais alto dos pugilistas, mas a sua altura \u00e9 perfeita para a categoria de pesos leves. Com 61 quilos, combina pot\u00eancia e agilidade. N\u00e3o \u00e9 por acaso que tem a alcunha de \"The Flash\". Move-se t\u00e3o depressa que os seus advers\u00e1rios t\u00eam dificuldade em acompanh\u00e1-lo. Com apenas 25 anos, j\u00e1 deixou a sua marca na hist\u00f3ria do boxe. Mas n\u00e3o \u00e9 s\u00f3 a sua carreira desportiva que \u00e9 impressionante.<\/p>\n\n\n\n<p>Para al\u00e9m das suas vit\u00f3rias no ringue, Ryan acumulou uma fortuna avaliada em 10 milh\u00f5es de d\u00f3lares. Como \u00e9 que ele conseguiu isso? Claro que ganha muito com os seus combates, mas tamb\u00e9m assinou contratos com marcas de prest\u00edgio, atra\u00eddas pela sua imagem e popularidade nas redes sociais. Ganha muito dinheiro com cada murro, e isso \u00e9 apenas o come\u00e7o. Estamos a falar de um jovem que pode atingir novos patamares, tanto em termos de fama como de riqueza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Um f\u00edsico constru\u00eddo para a vit\u00f3ria<\/h3>\n\n\n\n<p>A sua altura e peso est\u00e3o optimizados para a categoria de pesos leves, e isso nota-se. Ryan Garcia tem o perfil perfeito para esta categoria. \u00c9 suficientemente grande para ter um grande alcance, mas suficientemente leve para continuar a ser extremamente r\u00e1pido. \u00c9 esta combina\u00e7\u00e3o que faz dele um pugilista formid\u00e1vel. O boxe n\u00e3o \u00e9 apenas uma quest\u00e3o de for\u00e7a bruta, \u00e9 tamb\u00e9m uma quest\u00e3o de estrat\u00e9gia, resist\u00eancia e timing. E com o seu tipo de corpo, Ryan destaca-se em todas estas \u00e1reas.<\/p>\n\n\n\n<p>Provavelmente j\u00e1 o viu nos seus v\u00eddeos de treino, onde mostra reflexos espantosos com uma velocidade de <a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/meilleur-sac-de-frappe-boxe\/\">atingido<\/a> que parece quase irreal. \u00c9 isso que torna os seus combates t\u00e3o espectaculares. E depois h\u00e1 a sua for\u00e7a mental. Aos 25 anos, j\u00e1 enfrentou momentos de d\u00favida e de dificuldades, mas sempre deu a volta por cima. N\u00e3o \u00e9 toda a gente que consegue lidar com tanta press\u00e3o numa idade t\u00e3o jovem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A carreira de Ryan Garcia: um in\u00edcio prometedor<\/h2>\n\n\n\n<p>Ryan Garcia \u00e9 a hist\u00f3ria de um mi\u00fado californiano que cresceu com o boxe no sangue. Desde muito cedo, foi imerso neste mundo, influenciado pelo seu pai, ele pr\u00f3prio um entusiasta do boxe. Ryan come\u00e7ou a treinar muito cedo e nunca mais olhou para tr\u00e1s. Com apenas 17 anos, tornou-se profissional e foi a\u00ed que tudo come\u00e7ou. Rapidamente se tornou o assunto de conversa nos c\u00edrculos de boxe. Com a sua t\u00e9cnica deslumbrante e o seu carisma natural, ganhou os seus primeiros combates profissionais com grande sucesso. Os seus advers\u00e1rios eram muitas vezes ultrapassados pela sua velocidade, e ele acumulou vit\u00f3rias mesmo antes de o seu nome ser realmente conhecido pelo p\u00fablico em geral.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Uma ascens\u00e3o mete\u00f3rica<\/h3>\n\n\n\n<p>Em apenas alguns anos, Ryan Garcia passou de \"jovem promissor\" a \"estrela em ascens\u00e3o do boxe\". A sua velocidade de golpe, sentido de oportunidade e capacidade de acabar com os advers\u00e1rios com nocautes espectaculares colocaram-no rapidamente na ribalta. Mas ele n\u00e3o descansou sobre os louros. Em vez de se contentar com o seu sucesso, continuou a trabalhar, a aperfei\u00e7oar a sua arte. Cada combate, cada assalto, cada sess\u00e3o de treino, tudo \u00e9 calculado para o ajudar a evoluir.<\/p>\n\n\n\n<p>Lembram-se do seu combate contra Luke Campbell em 2021? Nesse dia, Ryan Garcia provou que n\u00e3o era apenas um pugilista \"bling-bling\". Derrubado pela primeira vez em sua carreira, ele poderia ter desistido, mas n\u00e3o. Voltou a levantar-se, mostrou uma resist\u00eancia incr\u00edvel e terminou o combate com um nocaute magistral no 7\u00ba assalto. S\u00e3o momentos como este que nos mostram o verdadeiro car\u00e1cter de um campe\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Redes sociais: uma arma formid\u00e1vel para Ryan Garcia<\/h2>\n\n\n\n<p>Ryan Garcia \u00e9 a mistura perfeita de desporto e estrat\u00e9gia digital. Antes dele, poucos boxeadores tinham conseguido conquistar as redes sociais da mesma forma. Instagram, TikTok, Twitter, ele est\u00e1 em todo o lado. E n\u00e3o s\u00f3 para publicar fotografias suas em <keyword data-keyword-id=\"821\"><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/meilleur-gant-de-boxe-comparatif\/\">luvas de boxe<\/a><\/keyword>. Ryan compreendeu que as redes sociais n\u00e3o s\u00e3o apenas uma forma de se tornar conhecido, mas tamb\u00e9m uma ferramenta para comunicar diretamente com os seus f\u00e3s. Partilha as suas sess\u00f5es de treino, os seus momentos de descontra\u00e7\u00e3o e at\u00e9 partes da sua vida privada, tornando-o acess\u00edvel e pr\u00f3ximo dos seus milh\u00f5es de seguidores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A influ\u00eancia das redes sociais na sua carreira<\/h3>\n\n\n\n<p>As redes sociais tornaram-se uma alavanca poderosa na sua carreira. Gra\u00e7as a elas, criou uma comunidade de f\u00e3s dedicados que o apoiam em todas as fases da sua carreira. Mas, mais do que isso, atraiu tamb\u00e9m a aten\u00e7\u00e3o de patrocinadores e marcas, que o v\u00eaem como uma figura emblem\u00e1tica para os jovens. A sua capacidade de combinar o desempenho desportivo com o marketing digital \u00e9 impressionante. Foi gra\u00e7as a isso que conseguiu assinar contratos lucrativos com marcas como a Gatorade e a Gymshark.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os principais combates de Ryan Garcia<\/h2>\n\n\n\n<p>Ryan Garcia teve uma s\u00e9rie de destaques em sua carreira, mas se h\u00e1 uma luta que se destaca, \u00e9 aquela contra Luke Campbell. Em janeiro de 2021, numa luta pelo t\u00edtulo interino de pesos leves do WBC, Ryan foi mandado para o tapete pela primeira vez. Foi o momento da verdade. Como \u00e9 que ele iria reagir? Muitos teriam perdido o equil\u00edbrio, mas ele n\u00e3o. Levantou-se, recuperou o controlo do combate e terminou com um KO que ficar\u00e1 para a hist\u00f3ria. Este combate n\u00e3o s\u00f3 confirmou o seu talento, como tamb\u00e9m mostrou o cora\u00e7\u00e3o que ele tem.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Uma carreira cheia de promessas<\/h3>\n\n\n\n<p>At\u00e9 \u00e0 data, Ryan Garcia tem um registo de 23 vit\u00f3rias e apenas uma derrota. E apesar deste pequeno contratempo, continua a subir na classifica\u00e7\u00e3o. A sua ambi\u00e7\u00e3o \u00e9 clara: quer ser o melhor. Mas, para isso, ainda tem de se cruzar com os melhores. Em particular, fala-se de poss\u00edveis combates futuros contra Devin Haney ou Teofimo Lopez. Combates que, a realizarem-se, ser\u00e3o verdadeiros testes para ele.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Ryan Garcia \u00e9 muito mais do que um simples pugilista. Ele \u00e9 a personifica\u00e7\u00e3o de uma nova gera\u00e7\u00e3o de lutadores, aqueles que sabem como brilhar no ringue, mas tamb\u00e9m nas redes sociais. Com apenas 25 anos, j\u00e1 conseguiu o que muitos sonham fazer numa vida inteira. Mas isto \u00e9 apenas o come\u00e7o. Os f\u00e3s esperam ansiosamente para ver at\u00e9 onde ele vai chegar e, se me perguntarem, ele ainda n\u00e3o acabou de nos surpreender.<\/p>\n\n\n\n<p>Fontes : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4919\">Wiki do boxe <\/a><\/strong><\/p>\n\n\n\n<p>Ver tamb\u00e9m :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4920\"> S\u00edtio Web oficial dos veteranos<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Recapitula\u00e7\u00e3o r\u00e1pida do artigo em resumo Categoria Detalhes principais Nome completo Ryan Garcia Altura 1m78 Peso Leve (61kg) Idade 25 Fortuna 10 milh\u00f5es $ Introdu\u00e7\u00e3o Ryan Garcia \u00e9 um fen\u00f3meno do boxe neste momento. N\u00e3o \u00e9 poss\u00edvel percorrer o Instagram sem se deparar com ... <a title=\"Ryan Garcia: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/\" aria-label=\"Leia mais sobre Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune\">Ler mais<\/a><\/p>","protected":false},"author":2,"featured_media":2624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Ryan Garcia est bien plus qu\u2019un simple boxeur. Il est l\u2019incarnation d\u2019une nouvelle g\u00e9n\u00e9ration de combattants, ceux qui savent briller\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Ryan Garcia est bien plus qu\u2019un simple boxeur. Il est l\u2019incarnation d\u2019une nouvelle g\u00e9n\u00e9ration de combattants, ceux qui savent briller\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T16:16:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T16:16:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/image__24_-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"666\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-09-12T16:16:39+00:00\",\"dateModified\":\"2024-09-12T16:16:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/\"},\"wordCount\":1453,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/image__24_-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/\",\"name\":\"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/image__24_-removebg-preview.png\",\"datePublished\":\"2024-09-12T16:16:39+00:00\",\"dateModified\":\"2024-09-12T16:16:41+00:00\",\"description\":\"Ryan Garcia est bien plus qu\u2019un simple boxeur. Il est l\u2019incarnation d\u2019une nouvelle g\u00e9n\u00e9ration de combattants, ceux qui savent briller\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/image__24_-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/image__24_-removebg-preview.png\",\"width\":666,\"height\":375,\"caption\":\"Ryan Garcia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/ryan-garcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ryan Garcia: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio","description":"Ryan Garcia \u00e9 muito mais do que um simples pugilista. Ele \u00e9 a personifica\u00e7\u00e3o de uma nova gera\u00e7\u00e3o de lutadores, aqueles que sabem como brilhar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/","og_locale":"pt_PT","og_type":"article","og_title":"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Ryan Garcia est bien plus qu\u2019un simple boxeur. Il est l\u2019incarnation d\u2019une nouvelle g\u00e9n\u00e9ration de combattants, ceux qui savent briller","og_url":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/","og_site_name":"Boxeur PRO","article_published_time":"2024-09-12T16:16:39+00:00","article_modified_time":"2024-09-12T16:16:41+00:00","og_image":[{"width":666,"height":375,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/image__24_-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maxime","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-09-12T16:16:39+00:00","dateModified":"2024-09-12T16:16:41+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/"},"wordCount":1453,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/image__24_-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/","url":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/","name":"Ryan Garcia: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/image__24_-removebg-preview.png","datePublished":"2024-09-12T16:16:39+00:00","dateModified":"2024-09-12T16:16:41+00:00","description":"Ryan Garcia \u00e9 muito mais do que um simples pugilista. Ele \u00e9 a personifica\u00e7\u00e3o de uma nova gera\u00e7\u00e3o de lutadores, aqueles que sabem como brilhar.","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/image__24_-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/image__24_-removebg-preview.png","width":666,"height":375,"caption":"Ryan Garcia"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/pt\/ryan-garcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Ryan Garcia : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/pt\/#website","url":"https:\/\/boxeur-pro.fr\/pt\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/pt\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/pt\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/comments?post=2623"}],"version-history":[{"count":2,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2623\/revisions"}],"predecessor-version":[{"id":2630,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2623\/revisions\/2630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/media\/2624"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/media?parent=2623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/categories?post=2623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/tags?post=2623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}