{"id":2666,"date":"2024-09-25T16:28:14","date_gmt":"2024-09-25T14:28:14","guid":{"rendered":"https:\/\/boxeur-pro.fr\/?p=2666"},"modified":"2024-09-25T16:28:15","modified_gmt":"2024-09-25T14:28:15","slug":"jason-jackson-a-sua-historia-altura-peso-idade-fortuna","status":"publish","type":"post","link":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/","title":{"rendered":"Jason Jackson: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>Breve resumo do artigo<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th><strong>Aspeto<\/strong><\/th><th><strong>Detalhes<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Nome completo<\/strong><\/td><td>Jason Marlon Jackson<\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-taille\/\">Tamanho<\/a><\/strong><\/td><td><strong>6'1\u2033 (1,85 m)<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-poids\/\">Peso<\/a><\/strong><\/td><td><strong>77-80 kg (170-177 lbs)<\/strong><\/td><\/tr><tr><td><strong>Idade<\/strong><\/td><td><strong>33 anos de idade (nascido em 1990)<\/strong><\/td><\/tr><tr><td><strong><a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-fortune\/\">A fortuna<\/a><\/strong><\/td><td><strong>2 milh\u00f5es de euros<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Introdu\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p>Quando se trata de Jason Jackson, \u00e9 dif\u00edcil n\u00e3o ficar impressionado com a sua carreira. Oriundo de Kingston, na Jamaica, ele ganhou fama no mundo do MMA gra\u00e7as ao seu estilo agressivo e \u00e0 sua determina\u00e7\u00e3o inabal\u00e1vel. N\u00e3o \u00e9 por acaso que foi apelidado de \"The Ass-Kicking Machine\" - cada combate \u00e9 uma demonstra\u00e7\u00e3o de for\u00e7a, t\u00e9cnica e intelig\u00eancia. Neste artigo, vou mergulhar no mundo deste atleta, explorando a sua hist\u00f3ria, os seus sucessos, os seus desafios e, claro, as suas estat\u00edsticas impressionantes. Mas n\u00e3o se trata apenas de n\u00fameros, porque por detr\u00e1s de cada vit\u00f3ria est\u00e1 uma hist\u00f3ria, um percurso \u00fanico que fez de Jason Jackson um dos melhores lutadores da sua gera\u00e7\u00e3o.<\/p>\n\n\n\n<p>A hist\u00f3ria de Jackson \u00e9 uma hist\u00f3ria de resili\u00eancia. Durante os altos e baixos da sua carreira, nunca desistiu. Desde os seus primeiros dias em competi\u00e7\u00f5es locais at\u00e9 se tornar campe\u00e3o de pesos-m\u00e9dios no Bellator, demonstrou sempre uma vontade de vencer que poucos conseguem igualar. Vou mostrar-vos porque \u00e9 que este homem se tornou uma lenda e porque \u00e9 que ainda tem muito para oferecer ao mundo do MMA.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Jason Jackson: um lutador com uma carreira extraordin\u00e1ria<\/h2>\n\n\n\n<p>A carreira de Jason Jackson tem sido uma maratona. Nascido em Kingston, mudou-se rapidamente para os Estados Unidos para perseguir os seus sonhos. No in\u00edcio n\u00e3o foi f\u00e1cil, pois teve de fazer malabarismos com v\u00e1rios biscates para financiar os seus treinos. Mas o que distingue Jason dos outros \u00e9 a sua vontade inabal\u00e1vel. \u00c0 <strong>6'1\u2033 (1,85 m)<\/strong>Com uma constitui\u00e7\u00e3o atl\u00e9tica e uma flexibilidade rara para o seu tamanho, utilizou o seu f\u00edsico a seu favor desde o in\u00edcio da sua carreira.<\/p>\n\n\n\n<p>Visitar <strong>2012<\/strong>Ele fez sua estr\u00e9ia profissional contra futuros grandes nomes do UFC, como <strong>Colby Covington<\/strong>. Este in\u00edcio dif\u00edcil serviu apenas para aumentar a sua motiva\u00e7\u00e3o. As suas primeiras vit\u00f3rias colocaram-no rapidamente na ribalta. Mas isso n\u00e3o \u00e9 tudo: Jason \u00e9 um lutador vers\u00e1til. Seja em p\u00e9 ou no ch\u00e3o, ele sabe adaptar-se aos seus advers\u00e1rios. \u00c9 esta capacidade de evoluir e surpreender constantemente que o levou a conquistar t\u00edtulos em organiza\u00e7\u00f5es de prest\u00edgio como <strong>Titan FC<\/strong> e <strong>Bellator MMA<\/strong>.<\/p>\n\n\n\n<p>Mas o sucesso nunca \u00e9 linear. Ele tamb\u00e9m passou por momentos dif\u00edceis, incluindo les\u00f5es que o mantiveram afastado dos ringues. No entanto, cada obst\u00e1culo foi uma oportunidade para ele voltar mais forte. Em 2023, ganhou o campeonato de pesos m\u00e9dios no <strong>Bellator<\/strong>A sua perseveran\u00e7a \u00e9 uma li\u00e7\u00e3o para todos os que acompanham o desporto. A sua perseveran\u00e7a \u00e9 uma li\u00e7\u00e3o para todos os que acompanham o desporto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Os seus maiores sucessos no MMA<\/h3>\n\n\n\n<p>Os n\u00fameros falam por si quando se trata da carreira de Jason Jackson. Com um registo de <strong>18 vit\u00f3rias e apenas 5 derrotas<\/strong>dos quais <strong>6 por KO<\/strong>Ele provou que n\u00e3o estava ali pelo gozo. No entanto, as estat\u00edsticas n\u00e3o contam a hist\u00f3ria toda. O que torna Jason especial \u00e9 a sua abordagem met\u00f3dica ao combate. Na sua luta contra <strong>Paul Daley<\/strong>Por exemplo, foi capaz de utilizar a sua t\u00e9cnica para dominar um lutador que era conhecido pela sua poderosa <a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/meilleur-sac-de-frappe-boxe\/\">atingido<\/a>. Este combate, ganho por decis\u00e3o un\u00e2nime, marcou um ponto de viragem na sua carreira.<\/p>\n\n\n\n<p>Jason tamb\u00e9m \u00e9 conhecido pela sua capacidade de se preparar mentalmente para cada desafio. Antes de cada combate, estuda meticulosamente os seus advers\u00e1rios, detectando as suas fraquezas e explorando-as depois na jaula. Esta capacidade de pensar como um estratega ao mesmo tempo que \u00e9 um guerreiro permitiu-lhe estar entre os melhores. Os seus <strong>9 vit\u00f3rias por decis\u00e3o<\/strong> mostram que ele tamb\u00e9m sabe como lidar com a press\u00e3o ao longo do tempo, um elemento fundamental em batalhas de alto n\u00edvel.<\/p>\n\n\n\n<p>A luta contra a <strong>Douglas Lima<\/strong>um dos pontos altos da sua carreira, mostrou a versatilidade de Jason. Confrontado com um advers\u00e1rio formid\u00e1vel, manteve-se calmo e concentrado, utilizando as suas capacidades de luta livre para ganhar vantagem.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O homem por detr\u00e1s do lutador<\/h3>\n\n\n\n<p>Jason Jackson \u00e9 mais do que um lutador feroz. Por detr\u00e1s da alcunha de \"The Ass-Kicking Machine\" esconde-se um homem humilde, profundamente ligado \u00e0s suas ra\u00edzes jamaicanas e \u00e0 sua fam\u00edlia. Casado com Yaniuska, Jason \u00e9 um homem de fam\u00edlia amoroso, com dois filhos. <a href=\"https:\/\/boxeur-pro.fr\/pt\/boxe\/mike-tyson-enfants\/\">crian\u00e7as<\/a> e dois de um casamento anterior. Este equil\u00edbrio entre a sua vida pessoal e profissional \u00e9, sem d\u00favida, uma das raz\u00f5es do seu sucesso duradouro num desporto t\u00e3o exigente.<\/p>\n\n\n\n<p>A sua mudan\u00e7a para os Estados Unidos marcou n\u00e3o s\u00f3 o in\u00edcio da sua carreira profissional, mas tamb\u00e9m uma nova vida para ele e para a sua fam\u00edlia. Estabelecer-se em <strong>Miami<\/strong>Treina com alguns dos melhores lutadores do mundo, mantendo-se fiel \u00e0 sua identidade jamaicana. Sempre que entra na jaula, leva consigo a heran\u00e7a da sua terra natal.<\/p>\n\n\n\n<p>Fora da competi\u00e7\u00e3o, Jason tamb\u00e9m est\u00e1 envolvido na orienta\u00e7\u00e3o. Dedica tempo a ajudar os jovens talentos a desenvolverem-se, partilhando a sua experi\u00eancia e conselhos. \u00c9 um homem que compreende que a chave para o sucesso n\u00e3o reside apenas no desempenho f\u00edsico, mas tamb\u00e9m na atitude e na mentalidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uma fortuna bem merecida: 2 milh\u00f5es de d\u00f3lares<\/h2>\n\n\n\n<p>Com uma carreira t\u00e3o rica, n\u00e3o \u00e9 de admirar que Jason Jackson tenha acumulado uma fortuna respeit\u00e1vel. Estimada em <strong>2 milh\u00f5es de euros<\/strong>Esta soma representa n\u00e3o s\u00f3 os seus ganhos nos combates, mas tamb\u00e9m parcerias e oportunidades nos media. Embora os seus ganhos exactos nem sempre sejam divulgados, \u00e9 evidente que Jason capitalizou as suas vit\u00f3rias para construir uma fortuna s\u00f3lida.<\/p>\n\n\n\n<p>Ao contr\u00e1rio de outros atletas que gastam os seus ganhos rapidamente, Jason \u00e9 conhecido por ser met\u00f3dico na gest\u00e3o das suas finan\u00e7as. Investiu em bens imobili\u00e1rios e planeia desenvolver neg\u00f3cios ap\u00f3s a sua carreira nas MMA. N\u00e3o se trata apenas de ganhar dinheiro, trata-se tamb\u00e9m de assegurar o seu futuro e o da sua fam\u00edlia.<\/p>\n\n\n\n<p>O que distingue Jason \u00e9 a sua humilde abordagem \u00e0 riqueza. Ao contr\u00e1rio de alguns lutadores que gostam de ostentar a sua riqueza, Jackson prefere a discri\u00e7\u00e3o. Para ele, o mais importante \u00e9 garantir a estabilidade a longo prazo para os seus entes queridos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">As suas \u00faltimas batalhas e projectos futuros<\/h3>\n\n\n\n<p>Os \u00faltimos combates de Jason Jackson t\u00eam sido marcados por altos e baixos. Em <strong>2024<\/strong>perdeu o t\u00edtulo de pesos-m\u00e9dios para <strong>Ramazan Kuramagomedov<\/strong> numa batalha \u00e9pica. Mas longe de desistir, Jackson v\u00ea esta derrota como uma oportunidade para regressar mais forte. De facto, esse \u00e9 um dos seus pontos fortes: nunca v\u00ea a derrota como um fracasso, mas sim como uma li\u00e7\u00e3o a aprender para as batalhas futuras.<\/p>\n\n\n\n<p>Com o UFC na mira, Jason n\u00e3o esconde a sua ambi\u00e7\u00e3o de se juntar \u00e0 elite do MMA mundial. Para muitos especialistas, ele tem todas as capacidades necess\u00e1rias para brilhar nesta organiza\u00e7\u00e3o. O seu estilo, que combina for\u00e7a e estrat\u00e9gia, poder\u00e1 permitir-lhe impor-se contra os melhores lutadores do mundo. E quem sabe? Talvez dentro de alguns anos, Jason Jackson seja aclamado como um dos maiores da hist\u00f3ria do MMA.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conclus\u00e3o<\/strong><\/h3>\n\n\n\n<p>Em conclus\u00e3o, Jason Jackson \u00e9 muito mais do que um simples lutador. \u00c9 um homem com uma hist\u00f3ria inspiradora, um atleta inegavelmente talentoso e um modelo de perseveran\u00e7a. A sua carreira \u00e9 um exemplo para todos aqueles que procuram destacar-se no seu campo, seja no desporto ou em qualquer outro. \u00c0 <strong>33 anos de idade<\/strong>Com um historial impressionante e uma fortuna bem merecida, ainda tem muito para oferecer. E mesmo que os seus \u00faltimos combates tenham mostrado que ainda tem alguns desafios pela frente, \u00e9 evidente que Jason Jackson ainda n\u00e3o disse a sua \u00faltima palavra.<\/p>\n\n\n\n<p>Fontes : <strong><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boxe\" data-lasso-id=\"4983\">Wiki do boxe <\/a><\/strong><\/p>\n\n\n\n<p>Ver tamb\u00e9m :<strong><a href=\"https:\/\/pflmma.com\/\" data-lasso-id=\"4984\"> S\u00edtio Web oficial dos veteranos<\/a><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Recapitula\u00e7\u00e3o r\u00e1pida do artigo em resumo Detalhe do aspeto Nome completo Jason Marlon Jackson Altura 6'1 \u2033 (1.85 m) Peso 170-177 lbs (77-80 kg) Idade 33 (nascido em 1990) Fortuna $ 2 milh\u00f5es Introdu\u00e7\u00e3o Quando se trata de Jason Jackson, \u00e9 dif\u00edcil n\u00e3o ficar impressionado com seu ... <a title=\"Jason Jackson: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio\" class=\"read-more\" href=\"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/\" aria-label=\"Leia mais sobre Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\">Ler mais<\/a><\/p>","protected":false},"author":2,"featured_media":2671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[15],"class_list":["post-2666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxeurs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune<\/title>\n<meta name=\"description\" content=\"Pour conclure, Jason Jackson est bien plus qu&#039;un simple combattant. C&#039;est un homme avec une histoire inspirante, un athl\u00e8te\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\" \/>\n<meta property=\"og:description\" content=\"Pour conclure, Jason Jackson est bien plus qu&#039;un simple combattant. C&#039;est un homme avec une histoire inspirante, un athl\u00e8te\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/\" \/>\n<meta property=\"og:site_name\" content=\"Boxeur PRO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T14:28:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T14:28:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/\"},\"author\":{\"name\":\"Maxime\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\"},\"headline\":\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\",\"datePublished\":\"2024-09-25T14:28:14+00:00\",\"dateModified\":\"2024-09-25T14:28:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/\"},\"wordCount\":1467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"keywords\":[\"Boxeurs\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/\",\"name\":\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"datePublished\":\"2024-09-25T14:28:14+00:00\",\"dateModified\":\"2024-09-25T14:28:15+00:00\",\"description\":\"Pour conclure, Jason Jackson est bien plus qu'un simple combattant. C'est un homme avec une histoire inspirante, un athl\u00e8te\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/3120931-removebg-preview.png\",\"width\":586,\"height\":426,\"caption\":\"Jason Jackson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/jason-jackson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boxeur-pro.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/\",\"name\":\"Boxeur PRO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#organization\",\"name\":\"Boxeur PRO\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"contentUrl\":\"https:\\\/\\\/boxeur-pro.fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/LogoBoxeurProTransparent-1.png\",\"width\":709,\"height\":800,\"caption\":\"Boxeur PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/#\\\/schema\\\/person\\\/086d0ef78c9fe53d995cf72b71821937\",\"name\":\"Maxime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g\",\"caption\":\"Maxime\"},\"url\":\"https:\\\/\\\/boxeur-pro.fr\\\/pt\\\/author\\\/maxime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jason Jackson: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio","description":"Em conclus\u00e3o, Jason Jackson \u00e9 muito mais do que um simples lutador. \u00c9 um homem com uma hist\u00f3ria inspiradora, um atleta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/","og_locale":"pt_PT","og_type":"article","og_title":"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune","og_description":"Pour conclure, Jason Jackson est bien plus qu'un simple combattant. C'est un homme avec une histoire inspirante, un athl\u00e8te","og_url":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/","og_site_name":"Boxeur PRO","article_published_time":"2024-09-25T14:28:14+00:00","article_modified_time":"2024-09-25T14:28:15+00:00","og_image":[{"width":586,"height":426,"url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","type":"image\/png"}],"author":"Maxime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maxime","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#article","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/"},"author":{"name":"Maxime","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937"},"headline":"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune","datePublished":"2024-09-25T14:28:14+00:00","dateModified":"2024-09-25T14:28:15+00:00","mainEntityOfPage":{"@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/"},"wordCount":1467,"commentCount":0,"publisher":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#organization"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","keywords":["Boxeurs"],"articleSection":["Boxe"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/","url":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/","name":"Jason Jackson: hist\u00f3ria, altura, peso, idade, patrim\u00f3nio","isPartOf":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#primaryimage"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#primaryimage"},"thumbnailUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","datePublished":"2024-09-25T14:28:14+00:00","dateModified":"2024-09-25T14:28:15+00:00","description":"Em conclus\u00e3o, Jason Jackson \u00e9 muito mais do que um simples lutador. \u00c9 um homem com uma hist\u00f3ria inspiradora, um atleta","breadcrumb":{"@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#primaryimage","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/09\/3120931-removebg-preview.png","width":586,"height":426,"caption":"Jason Jackson"},{"@type":"BreadcrumbList","@id":"https:\/\/boxeur-pro.fr\/pt\/jason-jackson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boxeur-pro.fr\/"},{"@type":"ListItem","position":2,"name":"Jason Jackson : son histoire, taille, poids, \u00e2ge, fortune"}]},{"@type":"WebSite","@id":"https:\/\/boxeur-pro.fr\/pt\/#website","url":"https:\/\/boxeur-pro.fr\/pt\/","name":"Boxer PRO","description":"","publisher":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxeur-pro.fr\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/boxeur-pro.fr\/pt\/#organization","name":"Boxer PRO","url":"https:\/\/boxeur-pro.fr\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","contentUrl":"https:\/\/boxeur-pro.fr\/wp-content\/uploads\/2024\/01\/LogoBoxeurProTransparent-1.png","width":709,"height":800,"caption":"Boxeur PRO"},"image":{"@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/boxeur-pro.fr\/pt\/#\/schema\/person\/086d0ef78c9fe53d995cf72b71821937","name":"Maxime","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce38768ebaf5d044c623efd7ff10a6ad2e1bf4f59b1039f5295b8e35e82bb447?s=96&d=mm&r=g","caption":"Maxime"},"url":"https:\/\/boxeur-pro.fr\/pt\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/comments?post=2666"}],"version-history":[{"count":3,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2666\/revisions"}],"predecessor-version":[{"id":2678,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/posts\/2666\/revisions\/2678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/media\/2671"}],"wp:attachment":[{"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/media?parent=2666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/categories?post=2666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boxeur-pro.fr\/pt\/wp-json\/wp\/v2\/tags?post=2666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}